{"id":1680,"date":"2021-05-18T12:42:22","date_gmt":"2021-05-18T12:42:22","guid":{"rendered":"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/"},"modified":"2021-05-18T12:42:27","modified_gmt":"2021-05-18T12:42:27","slug":"nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten","status":"publish","type":"post","link":"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/","title":{"rendered":"Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? &#8211; Online Marketing nachrichten"},"content":{"rendered":"\n<p>\t\t\t\t\t\t\t\tKommentar Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? Es gibt kaum eine Brand im Konsumg\u00fcterbereich, die bei ihren Produkten nicht auf&amp;nbsp; Nachhaltigkeit setzt. Das ist gut so, findet Daniel Goihl, Co-Founder der Yoga-Marke Ikarus \u2013 denn jedes Unternehmen stehe in der Pflicht, sich mit dieser Thematik auseinanderzusetzen.<\/p>\n<p>\t\t\t\t\t\t\t\tStudie So wichtig ist die Customer Experience im B2B-HandelDas aktuelle B2Best Barometer von ECC K\u00f6ln und Creditreform zeigt: Customer Experience gewinnt auch im B2B-Handel immer mehr an Bedeutung &#8211; doch bei vielen Unternehmen besteht noch Handlungsbedarf, um den gesteigerten Anspr\u00fcchen der Kunden gerecht zu werden.<\/p>\n<p>\t\t\t\t\t\t\t\tKartellrecht Eigene E-Commerce-Abteilung: Bundeskartellamt nimmt Amazon st\u00e4rker ins Visier Eventuell wettbewerbswidriges Fehlverhalten von Amazon und anderen Online-Marktpl\u00e4tzen soll k\u00fcnftig gezielter untersucht und sanktioniert werden. Zu diesem Zweck hat das Bundeskartellamt eine Schwerpunktabteilung E-Commerce ins Leben gerufen.<\/p>\n<p>\t\t\t\t\t\t\t\tNachrichteninhalte &#8222;Facebook News&#8220; in Deutschland gestartet Seit Oktober 2019 gibt es &#8222;Facebook News&#8220; bereits in den USA. Jetzt startet die Kooperation zwischen Medienh\u00e4usern und der Plattform auch in Deutschland.<\/p>\n<p>\t\t\t\t\t\t\t\tPwC-StudieVon der Corona-Krise profitiert der Online-Handel &#8211; und der &#8222;Laden um die Ecke&#8220; Von der Corona-Krise profitierte nicht nur der Online-Handel. Einer aktuellen PwC-Studie zufolge erlebte auch der &#8222;Laden um die Ecke&#8220; eine Renaissance.<\/p>\n<p>\t\t\t\t\t\t\t\tUnterst\u00fctzung f\u00fcr Prime Video M\u00f6gliche \u00dcbernahme: Amazon ist an MGM-Filmstudios interessiert Amazon scheint an den Metro-Goldwyn-Mayer (MGM)-Filmstudios interessiert. Verhandlungspreis sollen neun Milliarden US-Dollar (7,4 Milliarden Euro) sein. Mit dem Filmstudio k\u00f6nnte Amazon seinen Streaming-Dienst Prime Video im zunehmend harten Wettbewerb st\u00e4rken.<\/p>\n<p>\t\t\t\t\t\t\t\tSocial Media Facebook und Axel Springer vereinbaren globale Zusammenarbeit Axel Springer und Facebook haben sich nach jahrelangen Diskussionen \u00fcberraschend auf eine umfassende Zusammenarbeit verst\u00e4ndigt. Der Deal umfasst auch Videoinhalte aus dem Springer-Konzern.<\/p>\n<p>\t\t\t\t\t\t\t\tFinanzierungsrunde Ankorstore sammelt 100 Millionen US-Dollar ein Der B2B-Marktplatz Ankorstore hat eine Series-B-Finanzerungsrunde \u00fcber 100 Millionen US-Dollar abgeschlossen. Das franz\u00f6sische Start-up erm\u00f6glicht Einzelh\u00e4ndlern eine unkomplizierte Zusammenarbeit mit Herstellern aus ganz Europa.<\/p>\n<p>\t\t\t\t\t\t\t\tQuick-Commerce-AnbieterGorillas plant Schweiz-Expansion Stellengesuche zeigen: Offenbar plant der Lieferdienst Gorillas seinen Markteintritt in der Schweiz &#8211; und d\u00fcrfte damit anderen Anbietern mit seinem ultraschnellen Service ordentlich Druck machen.<\/p>\n<p>\t\t\t\t\t\t\t\tNeues Verteilzentrum Amazon st\u00f6\u00dft auf Widerstand f\u00fcr Neubau in Kissing Der Online-Riese Amazon will am S\u00fcdrand Augsburgs ein neues Verteilzentrum errichten &#8211; und st\u00f6\u00dft dabei auf unerwarteten Widerstand der Gemeinde. Dabei w\u00e4re ein geeignetes Gel\u00e4nde verf\u00fcgbar. Doch die Standortwahl wirft noch weitere Fragen auf.<\/p>\n<p>\t\t\t\t\t\t\t\tNach 243 Jahren Britisches Warenhaus Debenhams schlie\u00dft Filialen &#8211; Online Shop l\u00e4uft weiter Die insolvente britische Kaufhauskette Debenhams hat ihre letzten Filialen geschlossen &#8211; nach 243 Jahren. Den Markennamen Debenhams und den Online Shop wird es weiterhin geben. Sie gingen zu Beginn des Jahres an den Internet-Modeh\u00e4ndler Boohoo.<\/p>\n<p>\t\t\t\t\t\t\t\tSocial Media-Studie TikTok wird als Verkaufskanal immer relevanterTikTok ist einer der beliebtesten Social-Media-Kan\u00e4le der jungen Zielgruppe. Ein Potenzial, das auch immer mehr Unternehmen im Bereich Social Commerce nutzen sollten, wie eine Studie des ECC K\u00f6ln zeigt.<\/p>\n<p>\t\t\t\t\t\t\t\tApp Store Apple: Eine Million problematischer Apps abgelehnt oder entfernt Apple hat in seinem App Store im vergangenen Jahr nahezu eine Million problematischer Apps entfernt &#8211; und rund eine Million Updates abgelehnt.<\/p>\n<p>\t\t\t\t\t\t\t\tZweiter Anlauf WhatsApp f\u00fchrt neue Datenschutz-Bestimmungen ein Seit Monaten gibt es Aufregung um die neuen Datenschutz-Bestimmungen bei WhatsApp. Nach viel Kritik verschob Facebooks Chat-App die Einf\u00fchrung. Die \u00c4nderungen werden jetzt sanfter umgesetzt.<\/p>\n<p>\t\t\t\t\t\t\t\tPodcast-EpisodeTouch Point: Flyeralarm &#8211; vom Druckerei-Start-up zum E-Commerce-SchwergewichtBrosch\u00fcren, Visitenkarten, Werbeartikel &#8211; Fyleralarm bedruckt so ziemlich alles, was man sich vorstellen kann. Wie der Mittelst\u00e4ndler mit Unternehmergeist und einer &#8222;Einfach-Machen-Mentalit\u00e4t&#8220; Erfolgsgeschichte geschrieben hat, verr\u00e4t CMO Simone Nierhaus im Podcast.<\/p>\n<p>\t\t\t\t\t\t\t\tSoftware 102 Millionen Euro Strafe f\u00fcr Google in Italien Internet-Riese Google muss in Italien eine Wettbewerbsstrafe zahlen &#8211; der Grund: eine App f\u00fcr Elektrofahrzeuge nicht in seine Plattform Android Auto aufgenommen.<\/p>\n<p>\t\t\t\t\t\t\t\tUS-ElektroautobauerTesla stoppt Bitcoin-Zahlungen &#8211; Krypto-W\u00e4hrungen brechen ein Wegen Umweltbedenken angesichts des hohen Stromverbrauchs hat Tesla Zahlungen mit der Kryptow\u00e4hrung Bitcoin eingestellt. Musks Tweet lie\u00df den Bitcoin-Preis schlagartig um Tausende US-Dollar abst\u00fcrzen.<\/p>\n<p>\t\t\t\t\t\t\t\tOnline Strategy Consultant im Bereich Online Marketing &amp; Social Media (Kaufmann \/ Betriebswirt o. \u00e4.)\u00a0\u00a0OnlineMarketing.de<\/p>\n<p>\t\t\t\t\t\t\t\tNeue Marketing-Kampagne f\u00fcr den Tagungsstandort Wien \u00bb news | tma-online\u00a0\u00a0tma &#8211; Travel Management Austria<\/p>\n<p>\t\t\t\t\t\t\t\tKampf der Super-Apps Lieferando bietet Lebensmittel-Lieferungen an Der Kampf der Super-Apps spitzt sich zu: Anwendungen wie Delivery Hero und Foodpanda wollen Lieferando Konkurrenz machen &#8211; diese indes greifen selbst an, und zwar die Lebensmittel-Lieferanten: Geplant sind Supermarkt-Lieferungen von innerhalb einer halben Stunde.<\/p>\n<p>\t\t\t\t\t\t\t\tLieferando-KonkurrenzUber startet Essenlieferdienst Eats in Berlin Essen nach Hause liefern &#8211; das ist in der Corona-Pandemie zu einem lukrativen Gesch\u00e4ft geworden. Nun legt auch der Fahrdienst-Vermittler Uber los.<\/p>\n<p>\t\t\t\t\t\t\t\tOnline-H\u00e4ndler Von Hawesko bis Zooplus: E-Commerce boomt \u00fcber alle Branchen hinweg Der Online-Handel boomt &#8211; \u00fcber alle Branchen hinweg. Das zeigen einmal mehr die Quartalszahlen der E-Commerce-Player Westwing, Zooplus, Hawesko und Global Fashion Group.<\/p>\n<p>\t\t\t\t\t\t\t\tDACH-Studie Wie E-Mail-Portale beim Branding und Vertrieb unterst\u00fctzen\u00dcber 90 Prozent der 16- bis 35-J\u00e4hrigen nutzen die E-Mail sowohl f\u00fcr private als auch f\u00fcr formelle Kommunikation. Das E-Mail-Postfach ist die zentrale Plattform in der gesamten digitalen Customer Journey und hilft beim Branding und im Vertrieb.<\/p>\n<p>\t\t\t\t\t\t\t\tMobile Commerce Start-upRezolve erreicht Milliarden Bewertung und expandiert nach Europa Zum Start in Deutschland hat die mobile Payment- und Engagement-Plattform Rezolve ihre Bewertung auf mehr als eine Milliarde US-Dollar erh\u00f6ht. Damit erreicht das Londoner Start-up den Unicorn-Status.<\/p>\n<p>\t\t\t\t\t\t\t\tPortfolio-AusbauDelivery Hero will wieder in Deutschland Fu\u00df fassen Im Dezember 2018 verkaufte Delivery Hero sein Deutschland-Gesch\u00e4ft f\u00fcr fast eine Milliarde Euro an den niederl\u00e4ndischen Rivalen Takeaway, zu dem Lieferando geh\u00f6rt. Nun will der Essens-Lieferdienst hierzulande wieder Fu\u00df fassen &#8211; und sein Lieferportfolio erweitern.<\/p>\n<p>\t\t\t\t\t\t\t\tOnline Shopper-ReportAmazon bleibt Nummer eins f\u00fcr deutsche Online-K\u00e4ufer Der E-Commerce-Dienstleister Pattern hat untersucht, wie sich das Kaufverhalten im Netz im letzten Jahr ver\u00e4ndert hat. Daraus geht klar hervor, dass Amazon nach wie vor der Favorit unter den deutschen Online-Shoppern ist.<\/p>\n<p>\t\t\t\t\t\t\t\tBeauty-PlattformDouglas: Rekordums\u00e4tze im Online-Gesch\u00e4ft W\u00e4hrend das station\u00e4re Filialgesch\u00e4ft weiterhin Corona-bedingt schw\u00e4chelt, verzeichnet Douglas im E-Commerce neue Rekordums\u00e4tze. So verzeichnet die Beauty-Plattform im Online-Handel ein Umsatzplus von 75,5 Prozent im Vergleich zum Vorjahresquartal.<\/p>\n<p>\t\t\t\t\t\t\t\tSenior Online Marketing Manager (m\/w\/d) Job bei LIQID Investments GmbH in Berlin, Germany\u00a0\u00a0Gr\u00fcnderszene<\/p>\n<p>\t\t\t\t\t\t\t\tM\u00f6gliche Steuernachzahlungen EU-Gericht urteilt zu Verg\u00fcnstigungen f\u00fcr Amazon &amp;amp; Co. Amazon soll nach dem Willen der EU-Kommission rund 250 Millionen Euro Steuern in Luxemburg nachzahlen. Beide Seiten halten die Forderung f\u00fcr v\u00f6llig ungerechtfertigt. Jetzt soll ein Gericht entscheiden.<\/p>\n<p>\t\t\t\t\t\t\t\tKundenbindung Studie: \u00dcber 80 Prozent der Konsumenten nutzen Loyalty-Programme Kundenbindungsprogramme sind inzwischen weit verbreitet. Die Konsumenten wollen Punkte sammeln, um damit Vorteile zu erhalten, so eine aktuelle Studie. Die App hat dabei die Plastikkarte weitgehend verdr\u00e4ngt.<\/p>\n<p>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.newslocker.com\/de-de\/branche\/online-marketing\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafr\/\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kommentar Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? Es gibt kaum eine Brand im Konsumg\u00fcterbereich, die bei ihren Produkten nicht auf&amp;nbsp; Nachhaltigkeit setzt. Das ist gut so, findet Daniel Goihl, Co-Founder der Yoga-Marke Ikarus \u2013 denn jedes Unternehmen stehe in der Pflicht, sich mit dieser Thematik auseinanderzusetzen. Studie So wichtig ist die Customer Experience [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? - Online Marketing nachrichten - Selected News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? - Online Marketing nachrichten - Selected News\" \/>\n<meta property=\"og:description\" content=\"Kommentar Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? Es gibt kaum eine Brand im Konsumg\u00fcterbereich, die bei ihren Produkten nicht auf&amp;nbsp; Nachhaltigkeit setzt. Das ist gut so, findet Daniel Goihl, Co-Founder der Yoga-Marke Ikarus \u2013 denn jedes Unternehmen stehe in der Pflicht, sich mit dieser Thematik auseinanderzusetzen. Studie So wichtig ist die Customer Experience [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/\" \/>\n<meta property=\"og:site_name\" content=\"Selected News\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-18T12:42:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-18T12:42:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/selectednews.info\/de\/wp-content\/uploads\/sites\/13\/2021\/05\/Nachhaltigkeit-beim-Online-Shopping-Sind-Kunden-schon-bereit-dafuer-Online.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"selectednews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"selectednews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/de\\\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/de\\\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\\\/\"},\"author\":{\"name\":\"selectednews\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/de\\\/#\\\/schema\\\/person\\\/b79ac6c3f85e7d3fd825ccfaa9a91671\"},\"headline\":\"Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? &#8211; Online Marketing nachrichten\",\"datePublished\":\"2021-05-18T12:42:22+00:00\",\"dateModified\":\"2021-05-18T12:42:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/de\\\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\\\/\"},\"wordCount\":1115,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/de\\\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2021\\\/05\\\/Nachhaltigkeit-beim-Online-Shopping-Sind-Kunden-schon-bereit-dafuer-Online.jpg\",\"articleSection\":[\"MARKETING NEWS\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/de\\\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/de\\\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\\\/\",\"url\":\"https:\\\/\\\/selectednews.info\\\/de\\\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\\\/\",\"name\":\"Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? - Online Marketing nachrichten - Selected News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/de\\\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/de\\\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2021\\\/05\\\/Nachhaltigkeit-beim-Online-Shopping-Sind-Kunden-schon-bereit-dafuer-Online.jpg\",\"datePublished\":\"2021-05-18T12:42:22+00:00\",\"dateModified\":\"2021-05-18T12:42:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/de\\\/#\\\/schema\\\/person\\\/b79ac6c3f85e7d3fd825ccfaa9a91671\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/de\\\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/de\\\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/de\\\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/selectednews.info\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2021\\\/05\\\/Nachhaltigkeit-beim-Online-Shopping-Sind-Kunden-schon-bereit-dafuer-Online.jpg\",\"contentUrl\":\"https:\\\/\\\/selectednews.info\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2021\\\/05\\\/Nachhaltigkeit-beim-Online-Shopping-Sind-Kunden-schon-bereit-dafuer-Online.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? - Online Marketing nachrichten\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/de\\\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/selectednews.info\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? &#8211; Online Marketing nachrichten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/selectednews.info\\\/de\\\/\",\"name\":\"Selected News\",\"description\":\"Selected News Germany\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/selectednews.info\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/de\\\/#\\\/schema\\\/person\\\/b79ac6c3f85e7d3fd825ccfaa9a91671\",\"name\":\"selectednews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df47a104cb5967d31c3340cf1cb4b49088cf27c3d8168f31a99c0b2fe0ef55c1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df47a104cb5967d31c3340cf1cb4b49088cf27c3d8168f31a99c0b2fe0ef55c1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df47a104cb5967d31c3340cf1cb4b49088cf27c3d8168f31a99c0b2fe0ef55c1?s=96&d=mm&r=g\",\"caption\":\"selectednews\"},\"url\":\"https:\\\/\\\/selectednews.info\\\/de\\\/author\\\/emely\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? - Online Marketing nachrichten - Selected News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/","og_locale":"de_DE","og_type":"article","og_title":"Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? - Online Marketing nachrichten - Selected News","og_description":"Kommentar Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? Es gibt kaum eine Brand im Konsumg\u00fcterbereich, die bei ihren Produkten nicht auf&amp;nbsp; Nachhaltigkeit setzt. Das ist gut so, findet Daniel Goihl, Co-Founder der Yoga-Marke Ikarus \u2013 denn jedes Unternehmen stehe in der Pflicht, sich mit dieser Thematik auseinanderzusetzen. Studie So wichtig ist die Customer Experience [&hellip;]","og_url":"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/","og_site_name":"Selected News","article_published_time":"2021-05-18T12:42:22+00:00","article_modified_time":"2021-05-18T12:42:27+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/selectednews.info\/de\/wp-content\/uploads\/sites\/13\/2021\/05\/Nachhaltigkeit-beim-Online-Shopping-Sind-Kunden-schon-bereit-dafuer-Online.jpg","type":"image\/jpeg"}],"author":"selectednews","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"selectednews","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/#article","isPartOf":{"@id":"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/"},"author":{"name":"selectednews","@id":"https:\/\/selectednews.info\/de\/#\/schema\/person\/b79ac6c3f85e7d3fd825ccfaa9a91671"},"headline":"Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? &#8211; Online Marketing nachrichten","datePublished":"2021-05-18T12:42:22+00:00","dateModified":"2021-05-18T12:42:27+00:00","mainEntityOfPage":{"@id":"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/"},"wordCount":1115,"commentCount":0,"image":{"@id":"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/de\/wp-content\/uploads\/sites\/13\/2021\/05\/Nachhaltigkeit-beim-Online-Shopping-Sind-Kunden-schon-bereit-dafuer-Online.jpg","articleSection":["MARKETING NEWS"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/","url":"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/","name":"Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? - Online Marketing nachrichten - Selected News","isPartOf":{"@id":"https:\/\/selectednews.info\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/#primaryimage"},"image":{"@id":"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/de\/wp-content\/uploads\/sites\/13\/2021\/05\/Nachhaltigkeit-beim-Online-Shopping-Sind-Kunden-schon-bereit-dafuer-Online.jpg","datePublished":"2021-05-18T12:42:22+00:00","dateModified":"2021-05-18T12:42:27+00:00","author":{"@id":"https:\/\/selectednews.info\/de\/#\/schema\/person\/b79ac6c3f85e7d3fd825ccfaa9a91671"},"breadcrumb":{"@id":"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/#primaryimage","url":"https:\/\/selectednews.info\/de\/wp-content\/uploads\/sites\/13\/2021\/05\/Nachhaltigkeit-beim-Online-Shopping-Sind-Kunden-schon-bereit-dafuer-Online.jpg","contentUrl":"https:\/\/selectednews.info\/de\/wp-content\/uploads\/sites\/13\/2021\/05\/Nachhaltigkeit-beim-Online-Shopping-Sind-Kunden-schon-bereit-dafuer-Online.jpg","width":1200,"height":630,"caption":"Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? - Online Marketing nachrichten"},{"@type":"BreadcrumbList","@id":"https:\/\/selectednews.info\/de\/nachhaltigkeit-beim-online-shopping-sind-kunden-schon-bereit-dafuer-online-marketing-nachrichten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/selectednews.info\/de\/"},{"@type":"ListItem","position":2,"name":"Nachhaltigkeit beim Online-Shopping: Sind Kunden schon bereit daf\u00fcr? &#8211; Online Marketing nachrichten"}]},{"@type":"WebSite","@id":"https:\/\/selectednews.info\/de\/#website","url":"https:\/\/selectednews.info\/de\/","name":"Selected News","description":"Selected News Germany","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/selectednews.info\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/selectednews.info\/de\/#\/schema\/person\/b79ac6c3f85e7d3fd825ccfaa9a91671","name":"selectednews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/df47a104cb5967d31c3340cf1cb4b49088cf27c3d8168f31a99c0b2fe0ef55c1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/df47a104cb5967d31c3340cf1cb4b49088cf27c3d8168f31a99c0b2fe0ef55c1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/df47a104cb5967d31c3340cf1cb4b49088cf27c3d8168f31a99c0b2fe0ef55c1?s=96&d=mm&r=g","caption":"selectednews"},"url":"https:\/\/selectednews.info\/de\/author\/emely\/"}]}},"_links":{"self":[{"href":"https:\/\/selectednews.info\/de\/wp-json\/wp\/v2\/posts\/1680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/selectednews.info\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/selectednews.info\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/selectednews.info\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/selectednews.info\/de\/wp-json\/wp\/v2\/comments?post=1680"}],"version-history":[{"count":1,"href":"https:\/\/selectednews.info\/de\/wp-json\/wp\/v2\/posts\/1680\/revisions"}],"predecessor-version":[{"id":1682,"href":"https:\/\/selectednews.info\/de\/wp-json\/wp\/v2\/posts\/1680\/revisions\/1682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/selectednews.info\/de\/wp-json\/wp\/v2\/media\/1681"}],"wp:attachment":[{"href":"https:\/\/selectednews.info\/de\/wp-json\/wp\/v2\/media?parent=1680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/selectednews.info\/de\/wp-json\/wp\/v2\/categories?post=1680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/selectednews.info\/de\/wp-json\/wp\/v2\/tags?post=1680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}