{"id":2171,"date":"2019-09-17T11:25:25","date_gmt":"2019-09-17T11:25:25","guid":{"rendered":"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/"},"modified":"2019-09-17T11:25:26","modified_gmt":"2019-09-17T11:25:26","slug":"pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo","status":"publish","type":"post","link":"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/","title":{"rendered":"Pensioni ultime notizie, le sorti di quota 100 e le altre misure: cosa sta succedendo?"},"content":{"rendered":"<p><\/p>\n<p>                di Sissi<br \/>\n                17 Settembre 2019<\/p>\n<p>Pensioni ultime notizie: quali sono le sorti di quota 100 e delle altre misure? Scopriamo cosa sta succedendo con l\u2019entrata in scenda del Governo Conte bis, formato da Movimento 5 stelle e Pd. La collaborazione inedita e inaspettata tra le due forze politiche apre a scenari nuovi. Mentre con Salvini l\u2019unico obiettivo era eliminare definitivamente la Legge Fornero, ritenuta dannosa per i lavoratori e i pensionati, ora la linea potrebbe diventare pi\u00f9 morbida. Sta di fatto che, almeno per il momento, le pensioni quota 100 non sembrerebbero essere a rischio. Cosa succeder\u00e0 nei prossimi mesi? Vediamo quali sono le novit\u00e0 sulla riforma delle pensioni per il 2020.<\/p>\n<p>RIFORMA PENSIONI ULTIME NOTIZIE: COSA SUCCEDE NEL 2020?<br \/>\nNel 2020 non verr\u00e0 di certo eliminata la quota 100, misura che era stata fortemente voluta dalla Lega e che \u00e8 di durata triennale. La fase sperimentale relativa a questa tipologia di pensionamento anticipato termina infatti nel 2021. Si \u00e8 parlato per\u00f2 di possibili modifiche e miglioramenti, nel caso in cui fosse necessario farli. Per quanto riguarda invece l\u2019opzione donna, sembra essere tra le volont\u00e0 del Governo il fatto di prorogare ancora la misura.<\/p>\n<p>LA QUOTA 100 COSTA MENO DI ALTRE MISURE? ECCO I DATI<br \/>\nIntanto il Sole 24 Ore ha fatto emergere che non \u00e8 solo la quota 100 a pesare sulle casse dello Stato. Andando ad analizzare i dati emerge che su 341mila domande per andare in pensione che sono state presentate alla data del 10 settembre, 165mila riguardano pensionamenti anticipati alternativi alla quota 100. La quota 100 invece conta un numero di 175.999 richieste, delle quali ne sono state accolte 110.733.<br \/>\nRicordiamo che con le pensioni quota 100 si pu\u00f2 lasciare il lavoro a 62 anni di et\u00e0 con 38 anni di contributi versati. A quanto pare piacciono per\u00f2 anche altre misure ai cittadini. Stiamo parlando alle uscite anticipate per le quali \u00e8 previsto il blocco del vincolo alla speranza di vita fino al 2026. Negli ultimi mesi sembra essere in crescita la scelta di andare in pensione al raggiungimento di un certo numero di anni di contributi versati. E l\u2019opzione donna? Al 10 settembre le domande pervenute sono 20mila.<br \/>\nInsomma, sulla base di questi dati sar\u00e0 necessario comprendere in quale direzione vuole andare il nuovo Governo M5S-Pd. Sta di fatto che Luigi Di Maio, attuale Ministro degli Esteri, ha garantito che la riforma delle pensioni portata a casa con il precedente Governo non si tocca. Come si proceder\u00e0 quindi? Si attendono aggiornamenti nei prossimi giorni relativi alla riforma delle pensioni dell\u2019anno prossimo.<\/p>\n<p>\t\tPensioni ultime notizie, le sorti di quota 100 e le altre misure: cosa sta succedendo?<br \/>\n\t\tultima modifica:  2019-09-17T10:13:23+02:00<br \/>\n\t\tda Sissi<\/p>\n<p>            Leggi altri articoli di Economia<\/p>\n<p>        &#13;<\/p>\n<p>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.intopic.it\/rdrxml.php?n=17778899&#038;ai=1186647\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>di Sissi 17 Settembre 2019 Pensioni ultime notizie: quali sono le sorti di quota 100 e delle altre misure? Scopriamo cosa sta succedendo con l\u2019entrata in scenda del Governo Conte bis, formato da Movimento 5 stelle e Pd. La collaborazione inedita e inaspettata tra le due forze politiche apre a scenari nuovi. Mentre con Salvini [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2172,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novita-commerciali"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pensioni ultime notizie, le sorti di quota 100 e le altre misure: cosa sta succedendo? - Selected News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pensioni ultime notizie, le sorti di quota 100 e le altre misure: cosa sta succedendo? - Selected News\" \/>\n<meta property=\"og:description\" content=\"di Sissi 17 Settembre 2019 Pensioni ultime notizie: quali sono le sorti di quota 100 e delle altre misure? Scopriamo cosa sta succedendo con l\u2019entrata in scenda del Governo Conte bis, formato da Movimento 5 stelle e Pd. La collaborazione inedita e inaspettata tra le due forze politiche apre a scenari nuovi. Mentre con Salvini [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/\" \/>\n<meta property=\"og:site_name\" content=\"Selected News\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-17T11:25:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-17T11:25:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/selectednews.info\/it\/wp-content\/uploads\/sites\/9\/2019\/09\/1568719525_Pensioni-ultime-notizie-le-sorti-di-quota-100-e-le.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"selectednews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"selectednews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\\\/\"},\"author\":{\"name\":\"selectednews\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"headline\":\"Pensioni ultime notizie, le sorti di quota 100 e le altre misure: cosa sta succedendo?\",\"datePublished\":\"2019-09-17T11:25:25+00:00\",\"dateModified\":\"2019-09-17T11:25:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\\\/\"},\"wordCount\":447,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2019\\\/09\\\/1568719525_Pensioni-ultime-notizie-le-sorti-di-quota-100-e-le.jpg\",\"articleSection\":[\"NOVIT\u00c0 COMMERCIALI\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/it\\\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\\\/\",\"url\":\"https:\\\/\\\/selectednews.info\\\/it\\\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\\\/\",\"name\":\"Pensioni ultime notizie, le sorti di quota 100 e le altre misure: cosa sta succedendo? - Selected News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2019\\\/09\\\/1568719525_Pensioni-ultime-notizie-le-sorti-di-quota-100-e-le.jpg\",\"datePublished\":\"2019-09-17T11:25:25+00:00\",\"dateModified\":\"2019-09-17T11:25:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/it\\\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/selectednews.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2019\\\/09\\\/1568719525_Pensioni-ultime-notizie-le-sorti-di-quota-100-e-le.jpg\",\"contentUrl\":\"https:\\\/\\\/selectednews.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2019\\\/09\\\/1568719525_Pensioni-ultime-notizie-le-sorti-di-quota-100-e-le.jpg\",\"width\":1200,\"height\":700,\"caption\":\"pensioni ultime notizie quota 100 governo conte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/selectednews.info\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pensioni ultime notizie, le sorti di quota 100 e le altre misure: cosa sta succedendo?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/selectednews.info\\\/it\\\/\",\"name\":\"Selected News\",\"description\":\"Selected News Italy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/selectednews.info\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\",\"name\":\"selectednews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"caption\":\"selectednews\"},\"url\":\"https:\\\/\\\/selectednews.info\\\/it\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pensioni ultime notizie, le sorti di quota 100 e le altre misure: cosa sta succedendo? - Selected News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/","og_locale":"it_IT","og_type":"article","og_title":"Pensioni ultime notizie, le sorti di quota 100 e le altre misure: cosa sta succedendo? - Selected News","og_description":"di Sissi 17 Settembre 2019 Pensioni ultime notizie: quali sono le sorti di quota 100 e delle altre misure? Scopriamo cosa sta succedendo con l\u2019entrata in scenda del Governo Conte bis, formato da Movimento 5 stelle e Pd. La collaborazione inedita e inaspettata tra le due forze politiche apre a scenari nuovi. Mentre con Salvini [&hellip;]","og_url":"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/","og_site_name":"Selected News","article_published_time":"2019-09-17T11:25:25+00:00","article_modified_time":"2019-09-17T11:25:26+00:00","og_image":[{"width":1200,"height":700,"url":"https:\/\/selectednews.info\/it\/wp-content\/uploads\/sites\/9\/2019\/09\/1568719525_Pensioni-ultime-notizie-le-sorti-di-quota-100-e-le.jpg","type":"image\/jpeg"}],"author":"selectednews","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"selectednews","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/#article","isPartOf":{"@id":"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/"},"author":{"name":"selectednews","@id":"https:\/\/selectednews.info\/it\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"headline":"Pensioni ultime notizie, le sorti di quota 100 e le altre misure: cosa sta succedendo?","datePublished":"2019-09-17T11:25:25+00:00","dateModified":"2019-09-17T11:25:26+00:00","mainEntityOfPage":{"@id":"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/"},"wordCount":447,"commentCount":0,"image":{"@id":"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/it\/wp-content\/uploads\/sites\/9\/2019\/09\/1568719525_Pensioni-ultime-notizie-le-sorti-di-quota-100-e-le.jpg","articleSection":["NOVIT\u00c0 COMMERCIALI"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/","url":"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/","name":"Pensioni ultime notizie, le sorti di quota 100 e le altre misure: cosa sta succedendo? - Selected News","isPartOf":{"@id":"https:\/\/selectednews.info\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/#primaryimage"},"image":{"@id":"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/it\/wp-content\/uploads\/sites\/9\/2019\/09\/1568719525_Pensioni-ultime-notizie-le-sorti-di-quota-100-e-le.jpg","datePublished":"2019-09-17T11:25:25+00:00","dateModified":"2019-09-17T11:25:26+00:00","author":{"@id":"https:\/\/selectednews.info\/it\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"breadcrumb":{"@id":"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/#primaryimage","url":"https:\/\/selectednews.info\/it\/wp-content\/uploads\/sites\/9\/2019\/09\/1568719525_Pensioni-ultime-notizie-le-sorti-di-quota-100-e-le.jpg","contentUrl":"https:\/\/selectednews.info\/it\/wp-content\/uploads\/sites\/9\/2019\/09\/1568719525_Pensioni-ultime-notizie-le-sorti-di-quota-100-e-le.jpg","width":1200,"height":700,"caption":"pensioni ultime notizie quota 100 governo conte"},{"@type":"BreadcrumbList","@id":"https:\/\/selectednews.info\/it\/pensioni-ultime-notizie-le-sorti-di-quota-100-e-le-altre-misure-cosa-sta-succedendo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/selectednews.info\/it\/"},{"@type":"ListItem","position":2,"name":"Pensioni ultime notizie, le sorti di quota 100 e le altre misure: cosa sta succedendo?"}]},{"@type":"WebSite","@id":"https:\/\/selectednews.info\/it\/#website","url":"https:\/\/selectednews.info\/it\/","name":"Selected News","description":"Selected News Italy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/selectednews.info\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/selectednews.info\/it\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068","name":"selectednews","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","caption":"selectednews"},"url":"https:\/\/selectednews.info\/it\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/posts\/2171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/comments?post=2171"}],"version-history":[{"count":1,"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/posts\/2171\/revisions"}],"predecessor-version":[{"id":2173,"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/posts\/2171\/revisions\/2173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/media\/2172"}],"wp:attachment":[{"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/media?parent=2171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/categories?post=2171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/tags?post=2171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}