{"id":2206,"date":"2019-09-17T21:10:09","date_gmt":"2019-09-17T21:10:09","guid":{"rendered":"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/"},"modified":"2019-09-17T21:10:11","modified_gmt":"2019-09-17T21:10:11","slug":"sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero","status":"publish","type":"post","link":"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/","title":{"rendered":"Sace punta sul digitale per portare le imprese italiane all&#8217;estero"},"content":{"rendered":"<p>\n\t\t\t\t\t\tSace Simest, il polo per l&#8217;export e l&#8217;internazionalizzazione di Cassa Depositi e Prestiti, punta in maniera decisa sulla digitalizzazione dei servizi. Un percorso portato avanti negli ultimi tre anni, che ha consentito il lancio, lo scorso luglio, del portale Sacesimest.it, un vero e proprio ecosistema digitale che punta a coinvolgere 87mila piccole e medie imprese manifatturiere italiane nel mondo dei servizi e dei prodotti di Sace Simest per aiutarle a rafforzarne la dimensione internazionale e la competitivita&#8217; sui mercati esteri.\t\t\t\t\t<\/p>\n<p>&#8220;Per fruibilita&#8217;, ampiezza delle soluzioni offerte e livello di approfondimento di contenuti gratuiti, Sacesimest.it e&#8217; un unicum nel panorama italiano e delle agenzie di export credit. Ed e&#8217; un asset essenziale non solo per vendere i nostri servizi, ma soprattutto per creare le condizioni che permetteranno alle imprese italiane di approcciare di piu&#8217; e meglio i mercati esteri&#8221;, ha spiegato Alessandro Decio, amministratore delegato e direttore generale di Sace Simest.\u00a0&#8220;Cerchiamo di fornire quei supporti che possano sostenere la crescita delle imprese italiane all&#8217;estero &#8211; ha proseguito Decio &#8211; attraverso un percorso orchestrato e delineato insieme con gli altri attori che lavorano in questo campo.\t\t\t\t\t<\/p>\n<p>Un esempio? Un&#8217;azienda che ha buone potenzialita&#8217; di export ma non le ha ancora sfruttare potrebbe probabilmente trarre beneficio dalla disponibilita&#8217; di un temporary export manager, un professionista che lavora a stretto contatto con l&#8217;azienda e nell&#8217;azienda per indentificare i potenziali mercati e i distributori che possono dare accesso a questi mercati&#8221;. In poco piu&#8217; di due mesi di attivita&#8217;, il nuovo portale ha gia&#8217; registrato quasi 500mila pagine visitate da parte di circa 100mila utenti.(ITALPRESS)<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.intopic.it\/rdrxml.php?n=17786389&#038;ai=3559867\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sace Simest, il polo per l&#8217;export e l&#8217;internazionalizzazione di Cassa Depositi e Prestiti, punta in maniera decisa sulla digitalizzazione dei servizi. Un percorso portato avanti negli ultimi tre anni, che ha consentito il lancio, lo scorso luglio, del portale Sacesimest.it, un vero e proprio ecosistema digitale che punta a coinvolgere 87mila piccole e medie imprese [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2207,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novita-commerciali"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sace punta sul digitale per portare le imprese italiane all&#039;estero - Selected News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sace punta sul digitale per portare le imprese italiane all&#039;estero - Selected News\" \/>\n<meta property=\"og:description\" content=\"Sace Simest, il polo per l&#8217;export e l&#8217;internazionalizzazione di Cassa Depositi e Prestiti, punta in maniera decisa sulla digitalizzazione dei servizi. Un percorso portato avanti negli ultimi tre anni, che ha consentito il lancio, lo scorso luglio, del portale Sacesimest.it, un vero e proprio ecosistema digitale che punta a coinvolgere 87mila piccole e medie imprese [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/\" \/>\n<meta property=\"og:site_name\" content=\"Selected News\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-17T21:10:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-17T21:10:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/selectednews.info\/it\/wp-content\/uploads\/sites\/9\/2019\/09\/1568754610_Sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"817\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"selectednews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"selectednews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\\\/\"},\"author\":{\"name\":\"selectednews\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"headline\":\"Sace punta sul digitale per portare le imprese italiane all&#8217;estero\",\"datePublished\":\"2019-09-17T21:10:09+00:00\",\"dateModified\":\"2019-09-17T21:10:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\\\/\"},\"wordCount\":283,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2019\\\/09\\\/1568754610_Sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero.jpg\",\"articleSection\":[\"NOVIT\u00c0 COMMERCIALI\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/it\\\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\\\/\",\"url\":\"https:\\\/\\\/selectednews.info\\\/it\\\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\\\/\",\"name\":\"Sace punta sul digitale per portare le imprese italiane all'estero - Selected News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2019\\\/09\\\/1568754610_Sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero.jpg\",\"datePublished\":\"2019-09-17T21:10:09+00:00\",\"dateModified\":\"2019-09-17T21:10:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/it\\\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/selectednews.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2019\\\/09\\\/1568754610_Sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero.jpg\",\"contentUrl\":\"https:\\\/\\\/selectednews.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2019\\\/09\\\/1568754610_Sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero.jpg\",\"width\":817,\"height\":410,\"caption\":\"https:\\\/\\\/immagini.quotidianodiragusa.it\\\/immagini_articoli\\\/17-09-2019\\\/sace-punta-digitale-portare-imprese-italiane-estero-410.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/selectednews.info\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sace punta sul digitale per portare le imprese italiane all&#8217;estero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/selectednews.info\\\/it\\\/\",\"name\":\"Selected News\",\"description\":\"Selected News Italy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/selectednews.info\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/it\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\",\"name\":\"selectednews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"caption\":\"selectednews\"},\"url\":\"https:\\\/\\\/selectednews.info\\\/it\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sace punta sul digitale per portare le imprese italiane all'estero - Selected News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/","og_locale":"it_IT","og_type":"article","og_title":"Sace punta sul digitale per portare le imprese italiane all'estero - Selected News","og_description":"Sace Simest, il polo per l&#8217;export e l&#8217;internazionalizzazione di Cassa Depositi e Prestiti, punta in maniera decisa sulla digitalizzazione dei servizi. Un percorso portato avanti negli ultimi tre anni, che ha consentito il lancio, lo scorso luglio, del portale Sacesimest.it, un vero e proprio ecosistema digitale che punta a coinvolgere 87mila piccole e medie imprese [&hellip;]","og_url":"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/","og_site_name":"Selected News","article_published_time":"2019-09-17T21:10:09+00:00","article_modified_time":"2019-09-17T21:10:11+00:00","og_image":[{"width":817,"height":410,"url":"https:\/\/selectednews.info\/it\/wp-content\/uploads\/sites\/9\/2019\/09\/1568754610_Sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero.jpg","type":"image\/jpeg"}],"author":"selectednews","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"selectednews","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/#article","isPartOf":{"@id":"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/"},"author":{"name":"selectednews","@id":"https:\/\/selectednews.info\/it\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"headline":"Sace punta sul digitale per portare le imprese italiane all&#8217;estero","datePublished":"2019-09-17T21:10:09+00:00","dateModified":"2019-09-17T21:10:11+00:00","mainEntityOfPage":{"@id":"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/"},"wordCount":283,"commentCount":0,"image":{"@id":"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/it\/wp-content\/uploads\/sites\/9\/2019\/09\/1568754610_Sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero.jpg","articleSection":["NOVIT\u00c0 COMMERCIALI"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/","url":"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/","name":"Sace punta sul digitale per portare le imprese italiane all'estero - Selected News","isPartOf":{"@id":"https:\/\/selectednews.info\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/#primaryimage"},"image":{"@id":"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/it\/wp-content\/uploads\/sites\/9\/2019\/09\/1568754610_Sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero.jpg","datePublished":"2019-09-17T21:10:09+00:00","dateModified":"2019-09-17T21:10:11+00:00","author":{"@id":"https:\/\/selectednews.info\/it\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"breadcrumb":{"@id":"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/#primaryimage","url":"https:\/\/selectednews.info\/it\/wp-content\/uploads\/sites\/9\/2019\/09\/1568754610_Sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero.jpg","contentUrl":"https:\/\/selectednews.info\/it\/wp-content\/uploads\/sites\/9\/2019\/09\/1568754610_Sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero.jpg","width":817,"height":410,"caption":"https:\/\/immagini.quotidianodiragusa.it\/immagini_articoli\/17-09-2019\/sace-punta-digitale-portare-imprese-italiane-estero-410.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/selectednews.info\/it\/sace-punta-sul-digitale-per-portare-le-imprese-italiane-allestero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/selectednews.info\/it\/"},{"@type":"ListItem","position":2,"name":"Sace punta sul digitale per portare le imprese italiane all&#8217;estero"}]},{"@type":"WebSite","@id":"https:\/\/selectednews.info\/it\/#website","url":"https:\/\/selectednews.info\/it\/","name":"Selected News","description":"Selected News Italy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/selectednews.info\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/selectednews.info\/it\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068","name":"selectednews","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","caption":"selectednews"},"url":"https:\/\/selectednews.info\/it\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/posts\/2206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/comments?post=2206"}],"version-history":[{"count":1,"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/posts\/2206\/revisions"}],"predecessor-version":[{"id":2208,"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/posts\/2206\/revisions\/2208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/media\/2207"}],"wp:attachment":[{"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/media?parent=2206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/categories?post=2206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/selectednews.info\/it\/wp-json\/wp\/v2\/tags?post=2206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}