{"id":1402,"date":"2019-06-25T13:14:03","date_gmt":"2019-06-25T13:14:03","guid":{"rendered":"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/"},"modified":"2019-06-25T13:14:04","modified_gmt":"2019-06-25T13:14:04","slug":"se-desacelera-circulacion-de-billetes-y-monedas","status":"publish","type":"post","link":"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/","title":{"rendered":"Se desacelera circulaci\u00f3n de billetes y monedas"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p><span class=\"__cf_email__\" data-cfemail=\"620103101607100322070e170c0b14071011030e4c010d0f4c0f1a\">[email\u00a0protected]<\/span><br \/>La circulaci\u00f3n de billetes y monedas, al igual que la econom\u00eda, se est\u00e1 desacelerando.<br \/>Esto significa que la demanda del dinero en efectivo por parte del p\u00fablico en general est\u00e1 disminuyendo como reflejo de un menor avance de las actividades econ\u00f3micas.<\/p>\n<p>No obstante, hay planes para que en septiembre, para el aniversario 209 de la Independencia, se ponga en circulaci\u00f3n el nuevo billete de 200 pesos con la imagen de Hidalgo y Morelos, en sustituci\u00f3n de Sor Juana In\u00e9s de la Cruz.<\/p>\n<p>Para el caso del met\u00e1lico, el Banco de M\u00e9xico (Banxico) est\u00e1 reduciendo sus \u00f3rdenes de acu\u00f1aci\u00f3n de monedas, adem\u00e1s de que los bancos por su parte tienen inventarios acumulados que no hace tan urgente emitir por el momento m\u00e1s dinero met\u00e1lico.\u00a0<\/p>\n<\/p>\n<p>Sin embargo, la menor acu\u00f1aci\u00f3n est\u00e1 provocando que la Casa de Moneda de M\u00e9xico recorte sus planes de contrataci\u00f3n de personal eventual, afectando a miles de familias que se dedican a esta tarea en San Luis Potos\u00ed y que viene a agravar la situaci\u00f3n de despidos masivos por el cambio de directiva y austeridad presupuestal.<\/p>\n<p><strong>A\u00f1o electoral. <\/strong>Sobre la evoluci\u00f3n de la base monetaria, el gobernador del Banxico, Alejandro D\u00edaz de Le\u00f3n, inform\u00f3 que est\u00e1 creciendo a un menor ritmo respecto a 2018.<\/p>\n<p>Puntualiz\u00f3 que en las \u00faltimas semanas, el aumento en la circulaci\u00f3n de los billetes y monedas en poder de la gente ha sido de entre 4% y 5%.<\/p>\n<p>Lo anterior, explic\u00f3 el gobernador, se debe a la base de comparaci\u00f3n con la del a\u00f1o pasado, porque hoy no est\u00e1 presente el factor de las elecciones presidenciales que se celebraron en 2018.<\/p>\n<p>\u201cEs importante destacar que esta desaceleraci\u00f3n ha estado asociada a diferentes elementos, uno de ellos es que el a\u00f1o pasado fue electoral y a veces tiene un uso intensivo en efectivo\u201d, expuso D\u00edaz de Le\u00f3n durante la presentaci\u00f3n del Reporte de Estabilidad Financiera.<\/p>\n<p>En las menores \u00f3rdenes de acu\u00f1aci\u00f3n de monedas, el motivo es por la desaceleraci\u00f3n que se ha visto en la demanda por base monetaria y tambi\u00e9n, de alguna manera, las instituciones financieras tienen inventarios de monedas, a\u00f1adi\u00f3.<\/p>\n<p><strong>Inventarios. <\/strong>Otro elemento que agreg\u00f3 el gobernador central es que los bancos tienen suficientes material en sus inventarios.<\/p>\n<p>\u201cLo que apunta es que en los \u00faltimos trimestres ha habido un proceso en el cual las instituciones bancarias han acumulado inventarios suficientes de ese tipo de monedas y es un elemento muy natural del proceso de c\u00f3mo ponemos a circular los billetes y monedas\u201d, refiri\u00f3.<\/p>\n<p>Por eso, D\u00edaz de Le\u00f3n consider\u00f3 que sobre ese tema \u201cno hay algo adicional a destacar\u201d.<\/p>\n<p><strong>Moneda de 20 pesos.<\/strong> A finales de agosto de 2018, el Banxico present\u00f3 el nuevo billete de 500 pesos, en tono azulado y en el cual aparece la imagen del expresidente de M\u00e9xico Don Benito Ju\u00e1rez y con mejoras en las caracter\u00edsticas de seguridad para evitar su falsificaci\u00f3n.<\/p>\n<p>En ese entonces, el director general de Emisi\u00f3n del banco central, Alejandro Alegre, coment\u00f3 que para que la nueva pieza no se confundiera con el billete de 20 pesos, el cual tambi\u00e9n es de color azul y tiene el retrato de Ju\u00e1rez, hab\u00eda plana para acu\u00f1ar una moneda de 20 pesos de curso legal.<\/p>\n<p>Actualmente, Banxico cuenta con 13 monedas de esta denominaci\u00f3n que son conmemorativas.<\/p>\n<p>Si bien son piezas coleccionables, tienen valor de curso legal como cualquier otra moneda que circula diario en la econom\u00eda.<\/p>\n<p>La \u00faltima moneda que se acu\u00f1\u00f3 fue la conmemorativa a los 50 a\u00f1os del Plan Marina que puso a disposici\u00f3n del p\u00fablico en noviembre del a\u00f1o pasado.<\/p>\n<p><strong>Tardar\u00e1 en salir otra.<\/strong> Alejandro D\u00edaz de Le\u00f3n estim\u00f3 que a\u00fan hay espacio para que pueda salir otra moneda de 20 pesos.<\/p>\n<p>Estim\u00f3 que todav\u00eda pasar\u00e1 alg\u00fan tiempo m\u00e1s para que veamos una pieza nueva.<\/p>\n<p>\u201cAs\u00ed que todav\u00eda estamos a varios a\u00f1os de que esa decisi\u00f3n se materialice\u201d, expuso el gobernador.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.eluniversal.com.mx\/cartera\/se-desacelera-circulacion-de-billetes-y-monedas\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] [email\u00a0protected]La circulaci\u00f3n de billetes y monedas, al igual que la econom\u00eda, se est\u00e1 desacelerando.Esto significa que la demanda del dinero en efectivo por parte del p\u00fablico en general est\u00e1 disminuyendo como reflejo de un menor avance de las actividades econ\u00f3micas. No obstante, hay planes para que en septiembre, para el aniversario 209 de la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1403,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-negocios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se desacelera circulaci\u00f3n de billetes y monedas - Selected News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se desacelera circulaci\u00f3n de billetes y monedas - Selected News\" \/>\n<meta property=\"og:description\" content=\"[ad_1] [email\u00a0protected]La circulaci\u00f3n de billetes y monedas, al igual que la econom\u00eda, se est\u00e1 desacelerando.Esto significa que la demanda del dinero en efectivo por parte del p\u00fablico en general est\u00e1 disminuyendo como reflejo de un menor avance de las actividades econ\u00f3micas. No obstante, hay planes para que en septiembre, para el aniversario 209 de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/\" \/>\n<meta property=\"og:site_name\" content=\"Selected News\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-25T13:14:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-25T13:14:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/selectednews.info\/mx\/wp-content\/uploads\/sites\/8\/2019\/06\/Se-desacelera-circulaci\u00f3n-de-billetes-y-monedas.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"531\" \/>\n\t<meta property=\"og:image:height\" content=\"993\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"selectednews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"selectednews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/se-desacelera-circulacion-de-billetes-y-monedas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/se-desacelera-circulacion-de-billetes-y-monedas\\\/\"},\"author\":{\"name\":\"selectednews\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"headline\":\"Se desacelera circulaci\u00f3n de billetes y monedas\",\"datePublished\":\"2019-06-25T13:14:03+00:00\",\"dateModified\":\"2019-06-25T13:14:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/se-desacelera-circulacion-de-billetes-y-monedas\\\/\"},\"wordCount\":702,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/se-desacelera-circulacion-de-billetes-y-monedas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/06\\\/Se-desacelera-circulaci\u00f3n-de-billetes-y-monedas.gif\",\"articleSection\":[\"NOTICIAS DE NEGOCIOS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/mx\\\/se-desacelera-circulacion-de-billetes-y-monedas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/se-desacelera-circulacion-de-billetes-y-monedas\\\/\",\"url\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/se-desacelera-circulacion-de-billetes-y-monedas\\\/\",\"name\":\"Se desacelera circulaci\u00f3n de billetes y monedas - Selected News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/se-desacelera-circulacion-de-billetes-y-monedas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/se-desacelera-circulacion-de-billetes-y-monedas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/06\\\/Se-desacelera-circulaci\u00f3n-de-billetes-y-monedas.gif\",\"datePublished\":\"2019-06-25T13:14:03+00:00\",\"dateModified\":\"2019-06-25T13:14:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/se-desacelera-circulacion-de-billetes-y-monedas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/mx\\\/se-desacelera-circulacion-de-billetes-y-monedas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/se-desacelera-circulacion-de-billetes-y-monedas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/06\\\/Se-desacelera-circulaci\u00f3n-de-billetes-y-monedas.gif\",\"contentUrl\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/06\\\/Se-desacelera-circulaci\u00f3n-de-billetes-y-monedas.gif\",\"width\":531,\"height\":993,\"caption\":\"24jun19-monedas.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/se-desacelera-circulacion-de-billetes-y-monedas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se desacelera circulaci\u00f3n de billetes y monedas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/#website\",\"url\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/\",\"name\":\"Selected News\",\"description\":\"Selected News Mexico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\",\"name\":\"selectednews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"caption\":\"selectednews\"},\"url\":\"https:\\\/\\\/selectednews.info\\\/mx\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se desacelera circulaci\u00f3n de billetes y monedas - Selected News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/","og_locale":"es_MX","og_type":"article","og_title":"Se desacelera circulaci\u00f3n de billetes y monedas - Selected News","og_description":"[ad_1] [email\u00a0protected]La circulaci\u00f3n de billetes y monedas, al igual que la econom\u00eda, se est\u00e1 desacelerando.Esto significa que la demanda del dinero en efectivo por parte del p\u00fablico en general est\u00e1 disminuyendo como reflejo de un menor avance de las actividades econ\u00f3micas. No obstante, hay planes para que en septiembre, para el aniversario 209 de la [&hellip;]","og_url":"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/","og_site_name":"Selected News","article_published_time":"2019-06-25T13:14:03+00:00","article_modified_time":"2019-06-25T13:14:04+00:00","og_image":[{"width":531,"height":993,"url":"https:\/\/selectednews.info\/mx\/wp-content\/uploads\/sites\/8\/2019\/06\/Se-desacelera-circulaci\u00f3n-de-billetes-y-monedas.gif","type":"image\/gif"}],"author":"selectednews","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"selectednews","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/#article","isPartOf":{"@id":"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/"},"author":{"name":"selectednews","@id":"https:\/\/selectednews.info\/mx\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"headline":"Se desacelera circulaci\u00f3n de billetes y monedas","datePublished":"2019-06-25T13:14:03+00:00","dateModified":"2019-06-25T13:14:04+00:00","mainEntityOfPage":{"@id":"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/"},"wordCount":702,"commentCount":0,"image":{"@id":"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/mx\/wp-content\/uploads\/sites\/8\/2019\/06\/Se-desacelera-circulaci\u00f3n-de-billetes-y-monedas.gif","articleSection":["NOTICIAS DE NEGOCIOS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/","url":"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/","name":"Se desacelera circulaci\u00f3n de billetes y monedas - Selected News","isPartOf":{"@id":"https:\/\/selectednews.info\/mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/#primaryimage"},"image":{"@id":"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/mx\/wp-content\/uploads\/sites\/8\/2019\/06\/Se-desacelera-circulaci\u00f3n-de-billetes-y-monedas.gif","datePublished":"2019-06-25T13:14:03+00:00","dateModified":"2019-06-25T13:14:04+00:00","author":{"@id":"https:\/\/selectednews.info\/mx\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"breadcrumb":{"@id":"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/#primaryimage","url":"https:\/\/selectednews.info\/mx\/wp-content\/uploads\/sites\/8\/2019\/06\/Se-desacelera-circulaci\u00f3n-de-billetes-y-monedas.gif","contentUrl":"https:\/\/selectednews.info\/mx\/wp-content\/uploads\/sites\/8\/2019\/06\/Se-desacelera-circulaci\u00f3n-de-billetes-y-monedas.gif","width":531,"height":993,"caption":"24jun19-monedas.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/selectednews.info\/mx\/se-desacelera-circulacion-de-billetes-y-monedas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/selectednews.info\/mx\/"},{"@type":"ListItem","position":2,"name":"Se desacelera circulaci\u00f3n de billetes y monedas"}]},{"@type":"WebSite","@id":"https:\/\/selectednews.info\/mx\/#website","url":"https:\/\/selectednews.info\/mx\/","name":"Selected News","description":"Selected News Mexico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/selectednews.info\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/selectednews.info\/mx\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068","name":"selectednews","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","caption":"selectednews"},"url":"https:\/\/selectednews.info\/mx\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/selectednews.info\/mx\/wp-json\/wp\/v2\/posts\/1402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/selectednews.info\/mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/selectednews.info\/mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/selectednews.info\/mx\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/selectednews.info\/mx\/wp-json\/wp\/v2\/comments?post=1402"}],"version-history":[{"count":1,"href":"https:\/\/selectednews.info\/mx\/wp-json\/wp\/v2\/posts\/1402\/revisions"}],"predecessor-version":[{"id":1404,"href":"https:\/\/selectednews.info\/mx\/wp-json\/wp\/v2\/posts\/1402\/revisions\/1404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/selectednews.info\/mx\/wp-json\/wp\/v2\/media\/1403"}],"wp:attachment":[{"href":"https:\/\/selectednews.info\/mx\/wp-json\/wp\/v2\/media?parent=1402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/selectednews.info\/mx\/wp-json\/wp\/v2\/categories?post=1402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/selectednews.info\/mx\/wp-json\/wp\/v2\/tags?post=1402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}