{"id":7051,"date":"2021-06-12T07:25:47","date_gmt":"2021-06-12T04:25:47","guid":{"rendered":"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/"},"modified":"2021-06-12T07:25:50","modified_gmt":"2021-06-12T04:25:50","slug":"corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade","status":"publish","type":"post","link":"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/","title":{"rendered":"Corpcom \u00e9 a \u00fanica ag\u00eancia portuguesa premiada nos Sabre Awards &#8211; Meios &#038; Publicidade"},"content":{"rendered":"<p>\t\t\t\tPor Pedro Dur\u00e3es a 11 de Junho de 2021<\/p>\n<p>\t\t\tEntre as tr\u00eas ag\u00eancias que colocaram sete projectos nacionais na corrida aos Sabre Awards, a Corpcom acabou por ser a \u00fanica a sair vencedora na edi\u00e7\u00e3o deste ano. A campanha \u201cComo evitar uma crise numa tenda no topo de um Jeep\u201d, criada para comunicar o servi\u00e7o Campers da Hertz, valeu \u00e0 ag\u00eancia liderada por Jos\u00e9 Franco a distin\u00e7\u00e3o com um Diamond Sabre Award na categoria de Superior Achievement in Brand-Building. O projecto, recorde-se, surgia em destaque com duas nomea\u00e7\u00f5es na competi\u00e7\u00e3o Diamond Sabre Awards, que re\u00fane os trabalhos mais relevantes do \u00faltimo ano, tendo chegado igualmente \u00e0 shortlist para o The Sabre Award for Superior Achievement in Reputation Management.<br \/>\nLan\u00e7ado no final de 2019 e dirigido aos turistas, o servi\u00e7o Hertz Campers, que resultou de uma parceria entre a Hertz Portugal, a Jepp e as tendas portuguesas Topo, acabaria por ser redireccionado para os portugueses na sequ\u00eancia do impacto da pandemia sobre o neg\u00f3cio das rent-a-car, com a campanha criada pela Corpcom a apelar \u00e0 fuga dos sem\u00e1foros das praias procurando praias desertas espalhadas pela costa portuguesa.<br \/>\n\u201cCom a pandemia tudo mudou e foi cr\u00edtico reajustar o target deste produto, numa altura em que a pandemia provocava tamb\u00e9m p\u00e9ssimas not\u00edcias vindas dos EUA, com a fal\u00eancia da marca. Era necess\u00e1rio mostrar que a empresa estava viva em Portugal e, ao mesmo tempo, minimizar o impacto negativo no neg\u00f3cio pela perda de turistas\u201d, comenta Jos\u00e9 Franco. \u201cUsamos a pol\u00e9mica dos famosos sem\u00e1foros das praias e promovemos a visita a todas as praias do pa\u00eds. A utiliza\u00e7\u00e3o da Hertz Campers foi um \u00eaxito entre os portugueses e alavancou positivamente a marca numa das piores crises de sempre\u201d, salienta o managing partner da Corpcom.<\/p>\n<p>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.meiosepublicidade.pt\/2021\/06\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards\/?utm_source=rss&#038;utm_medium=rss&#038;utm_campaign=corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Pedro Dur\u00e3es a 11 de Junho de 2021 Entre as tr\u00eas ag\u00eancias que colocaram sete projectos nacionais na corrida aos Sabre Awards, a Corpcom acabou por ser a \u00fanica a sair vencedora na edi\u00e7\u00e3o deste ano. A campanha \u201cComo evitar uma crise numa tenda no topo de um Jeep\u201d, criada para comunicar o servi\u00e7o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7052,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias-de-marketing-online"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corpcom \u00e9 a \u00fanica ag\u00eancia portuguesa premiada nos Sabre Awards - Meios &amp; Publicidade - Selected News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corpcom \u00e9 a \u00fanica ag\u00eancia portuguesa premiada nos Sabre Awards - Meios &amp; Publicidade - Selected News\" \/>\n<meta property=\"og:description\" content=\"Por Pedro Dur\u00e3es a 11 de Junho de 2021 Entre as tr\u00eas ag\u00eancias que colocaram sete projectos nacionais na corrida aos Sabre Awards, a Corpcom acabou por ser a \u00fanica a sair vencedora na edi\u00e7\u00e3o deste ano. A campanha \u201cComo evitar uma crise numa tenda no topo de um Jeep\u201d, criada para comunicar o servi\u00e7o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Selected News\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-12T04:25:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-12T04:25:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/06\/Corpcom-e-a-unica-agencia-portuguesa-premiada-nos-Sabre-Awards.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"selectednews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"selectednews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\\\/\"},\"author\":{\"name\":\"selectednews\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"headline\":\"Corpcom \u00e9 a \u00fanica ag\u00eancia portuguesa premiada nos Sabre Awards &#8211; Meios &#038; Publicidade\",\"datePublished\":\"2021-06-12T04:25:47+00:00\",\"dateModified\":\"2021-06-12T04:25:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\\\/\"},\"wordCount\":325,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/Corpcom-e-a-unica-agencia-portuguesa-premiada-nos-Sabre-Awards.jpg\",\"articleSection\":[\"TEND\u00caNCIAS DE MARKETING ONLINE\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/pt\\\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\\\/\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\\\/\",\"name\":\"Corpcom \u00e9 a \u00fanica ag\u00eancia portuguesa premiada nos Sabre Awards - Meios & Publicidade - Selected News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/Corpcom-e-a-unica-agencia-portuguesa-premiada-nos-Sabre-Awards.jpg\",\"datePublished\":\"2021-06-12T04:25:47+00:00\",\"dateModified\":\"2021-06-12T04:25:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/pt\\\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/Corpcom-e-a-unica-agencia-portuguesa-premiada-nos-Sabre-Awards.jpg\",\"contentUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/Corpcom-e-a-unica-agencia-portuguesa-premiada-nos-Sabre-Awards.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Corpcom \u00e9 a \u00fanica ag\u00eancia portuguesa premiada nos Sabre Awards - Meios & Publicidade\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corpcom \u00e9 a \u00fanica ag\u00eancia portuguesa premiada nos Sabre Awards &#8211; Meios &#038; Publicidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/\",\"name\":\"Selected News\",\"description\":\"Selected News Portugal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\",\"name\":\"selectednews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"caption\":\"selectednews\"},\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corpcom \u00e9 a \u00fanica ag\u00eancia portuguesa premiada nos Sabre Awards - Meios & Publicidade - Selected News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/","og_locale":"pt_PT","og_type":"article","og_title":"Corpcom \u00e9 a \u00fanica ag\u00eancia portuguesa premiada nos Sabre Awards - Meios & Publicidade - Selected News","og_description":"Por Pedro Dur\u00e3es a 11 de Junho de 2021 Entre as tr\u00eas ag\u00eancias que colocaram sete projectos nacionais na corrida aos Sabre Awards, a Corpcom acabou por ser a \u00fanica a sair vencedora na edi\u00e7\u00e3o deste ano. A campanha \u201cComo evitar uma crise numa tenda no topo de um Jeep\u201d, criada para comunicar o servi\u00e7o [&hellip;]","og_url":"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/","og_site_name":"Selected News","article_published_time":"2021-06-12T04:25:47+00:00","article_modified_time":"2021-06-12T04:25:50+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/06\/Corpcom-e-a-unica-agencia-portuguesa-premiada-nos-Sabre-Awards.jpg","type":"image\/jpeg"}],"author":"selectednews","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"selectednews","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/#article","isPartOf":{"@id":"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/"},"author":{"name":"selectednews","@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"headline":"Corpcom \u00e9 a \u00fanica ag\u00eancia portuguesa premiada nos Sabre Awards &#8211; Meios &#038; Publicidade","datePublished":"2021-06-12T04:25:47+00:00","dateModified":"2021-06-12T04:25:50+00:00","mainEntityOfPage":{"@id":"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/"},"wordCount":325,"commentCount":0,"image":{"@id":"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/06\/Corpcom-e-a-unica-agencia-portuguesa-premiada-nos-Sabre-Awards.jpg","articleSection":["TEND\u00caNCIAS DE MARKETING ONLINE"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/","url":"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/","name":"Corpcom \u00e9 a \u00fanica ag\u00eancia portuguesa premiada nos Sabre Awards - Meios & Publicidade - Selected News","isPartOf":{"@id":"https:\/\/selectednews.info\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/#primaryimage"},"image":{"@id":"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/06\/Corpcom-e-a-unica-agencia-portuguesa-premiada-nos-Sabre-Awards.jpg","datePublished":"2021-06-12T04:25:47+00:00","dateModified":"2021-06-12T04:25:50+00:00","author":{"@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"breadcrumb":{"@id":"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/#primaryimage","url":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/06\/Corpcom-e-a-unica-agencia-portuguesa-premiada-nos-Sabre-Awards.jpg","contentUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/06\/Corpcom-e-a-unica-agencia-portuguesa-premiada-nos-Sabre-Awards.jpg","width":1200,"height":630,"caption":"Corpcom \u00e9 a \u00fanica ag\u00eancia portuguesa premiada nos Sabre Awards - Meios & Publicidade"},{"@type":"BreadcrumbList","@id":"https:\/\/selectednews.info\/pt\/corpcom-e-a-unica-agencia-portuguesa-premiada-nos-sabre-awards-meios-publicidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/selectednews.info\/pt\/"},{"@type":"ListItem","position":2,"name":"Corpcom \u00e9 a \u00fanica ag\u00eancia portuguesa premiada nos Sabre Awards &#8211; Meios &#038; Publicidade"}]},{"@type":"WebSite","@id":"https:\/\/selectednews.info\/pt\/#website","url":"https:\/\/selectednews.info\/pt\/","name":"Selected News","description":"Selected News Portugal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/selectednews.info\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068","name":"selectednews","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","caption":"selectednews"},"url":"https:\/\/selectednews.info\/pt\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/comments?post=7051"}],"version-history":[{"count":1,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7051\/revisions"}],"predecessor-version":[{"id":7053,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7051\/revisions\/7053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/media\/7052"}],"wp:attachment":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/media?parent=7051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/categories?post=7051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/tags?post=7051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}