{"id":7075,"date":"2021-06-14T07:36:44","date_gmt":"2021-06-14T04:36:44","guid":{"rendered":"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/"},"modified":"2021-06-14T07:36:47","modified_gmt":"2021-06-14T04:36:47","slug":"o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade","status":"publish","type":"post","link":"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/","title":{"rendered":"O ador\u00e1vel mundo da dist\u00e2ncia e da proximidade &#8211; Meios &#038; Publicidade"},"content":{"rendered":"<p>\t\t\tV\u00edtor Cunha, administrador da JLM&amp;Associados<br \/>\nDizem que a pandemia est\u00e1 mais calma e vamos voltar a ter uma vida mais normal. N\u00e3o sei bem o que \u00e9 uma vida normal \u2013 e nem sei se a desejo assim tanto -, mas n\u00e3o parece que possamos voltar ao tempo que era antes.<br \/>\nA for\u00e7a normativa da experi\u00eancia do teletrabalho e do novo com\u00e9rcio electr\u00f3nico deixaram marcas fortes e o mundo divide-se entre quem gosta, quem n\u00e3o gosta, quem quer combin\u00e1-los com o escrit\u00f3rio e a loja, outros ainda que t\u00eam opini\u00f5es escatol\u00f3gicas sobre o tema, o seu impacto na economia, na sociedade e no futuro da humanidade e dos animais dom\u00e9sticos.PUB<\/p>\n<p>\u00c9 evidente que h\u00e1 actividades onde o teletrabalho \u00e9 imposs\u00edvel: na agricultura, na ind\u00fastria, e mesmo em muito com\u00e9rcio e servi\u00e7os. Embora n\u00e3o se possa confundir teletrabalho com meios de disponibiliza\u00e7\u00e3o de servi\u00e7os ou bens \u00e0 dist\u00e2ncia, ambos acabam por andar em conjunto. No com\u00e9rcio electr\u00f3nico ou no teletrabalho o elemento matricial \u00e9 a dist\u00e2ncia da presta\u00e7\u00e3o ou da escolha para a obten\u00e7\u00e3o de um resultado que anteriormente era obtido presencialmente.<br \/>\nH\u00e1 servi\u00e7os ou com\u00e9rcio onde a experi\u00eancia tele \u00e9 poss\u00edvel, mas n\u00e3o \u00e9 agrad\u00e1vel. Haver\u00e1 espet\u00e1culo mais degradante do que uma embalagem de comida entregue em casa, fria, met\u00e1lica, inapresent\u00e1vel?<br \/>\nJ\u00e1 t\u00ednhamos tido no passado esta discuss\u00e3o sobre as vantagens do home delivery e do take away vs \u201cexperi\u00eancias reais\u201d. Para quem gosta de cinema: os filmes take away come\u00e7aram depois da massifica\u00e7\u00e3o das cassetes e com o aparecimento do \u201cclube de v\u00eddeo\u201d. Na altura, alguns desses clubes disponibilizavam a entrega e recolha em casa. A bendita tecnologia, em poucos anos, matou as cassetes e os clubes e pass\u00e1mos a ver cinema em casa em disco, depois em streaming, para al\u00e9m do cabo e do sat\u00e9lite.<br \/>\nSe repararem, a discuss\u00e3o \u00e9 sempre a mesma: um bife comido no restaurante \u00e9 melhor do que o mesmo bife entregue em casa? Resposta: \u00e9. E um filme visto numa sala \u00e9 melhor do que no ecr\u00e3 l\u00e1 de casa. Resposta: \u00e9. Mas, para ambos os casos, a resposta dada s\u00f3 \u00e9 v\u00e1lida se a carne e o filme forem bons. Um mau bife \u00e9 sempre um mau bife, um mau filme n\u00e3o passa a bom apenas porque o vemos numa sala boa.<br \/>\nIsto leva-nos ao tema da segmenta\u00e7\u00e3o. N\u00e3o foi preciso uma pandemia para comermos trash food entregue em casa, mas foi preciso uma pandemia para encomendarmos para casa um Wellington ou uma salada de caranguejo do Alasca. Ser\u00e1 que esta tend\u00eancia se vai manter, ou continuaremos apenas a pedir pizzas e hamb\u00fargueres? N\u00e3o tenho resposta, mas tenho prefer\u00eancias, como bom conservador: em casa o que \u00e9 de casa e na rua o que \u00e9 da rua.<br \/>\nDeixando a gastronomia: um bom auditor pode fazer bem o seu trabalho \u00e0 dist\u00e2ncia, ou tem que estar implantado na empresa auditada? Aqui h\u00e1 muitas d\u00favidas, na doutrina e na pr\u00e1tica, mas tudo indica que no momento em que as empresas forem absolutamente digitais esta discuss\u00e3o deixar\u00e1 de fazer sentido.<br \/>\nPodia continuar com exemplos mais ou menos gr\u00e1ficos sobre possibilidades e vantagens nestes temas da dist\u00e2ncia. J\u00e1 todos percebemos que estamos a meio de uma mudan\u00e7a que tinha come\u00e7ado antes, mas que n\u00e3o quisemos ver com aten\u00e7\u00e3o, especialmente no mercado de trabalho. Vai ser dif\u00edcil manter equipas empenhadas quando existe uma enorme divis\u00e3o dentro das organiza\u00e7\u00f5es quanto \u00e0s op\u00e7\u00f5es prevalecentes a tomar. Os mais novos, aparentemente, s\u00e3o quem mais prefere o teletrabalho. Ser\u00e3o tamb\u00e9m esses os mais prejudicados pela falta de apoio na sua forma\u00e7\u00e3o e acompanhamento. Os menos novos, esses, n\u00e3o aguentam nem a solid\u00e3o dom\u00e9stica nem o excesso de fam\u00edlia. Conhe\u00e7o alguns casos de pessoas que passaram a odiar os familiares mais pr\u00f3ximos por excesso de contacto. Ainda n\u00e3o se soube oficialmente de mortes ou agress\u00f5es graves que possam ser indiretamente imputadas ao v\u00edrus, at\u00e9 porque ningu\u00e9m quer engordar as estat\u00edsticas da dra. Gra\u00e7a. Mas pode ser que o tema nas\u00e7a e a\u00ed teremos mais uns dias de discuss\u00e3o e reflex\u00e3o sobre a nossa natureza e bondade. At\u00e9 l\u00e1, tenham um bom Ver\u00e3o.<br \/>\n*Por V\u00edtor Cunha, administrador da JLM&amp;Associados<\/p>\n<p>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.meiosepublicidade.pt\/2021\/06\/o-adoravel-mundo-da-distancia-e-da-proximidade\/?utm_source=rss&#038;utm_medium=rss&#038;utm_campaign=o-adoravel-mundo-da-distancia-e-da-proximidade\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00edtor Cunha, administrador da JLM&amp;Associados Dizem que a pandemia est\u00e1 mais calma e vamos voltar a ter uma vida mais normal. N\u00e3o sei bem o que \u00e9 uma vida normal \u2013 e nem sei se a desejo assim tanto -, mas n\u00e3o parece que possamos voltar ao tempo que era antes. A for\u00e7a normativa da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6888,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias-de-marketing-online"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O ador\u00e1vel mundo da dist\u00e2ncia e da proximidade - Meios &amp; Publicidade - Selected News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O ador\u00e1vel mundo da dist\u00e2ncia e da proximidade - Meios &amp; Publicidade - Selected News\" \/>\n<meta property=\"og:description\" content=\"V\u00edtor Cunha, administrador da JLM&amp;Associados Dizem que a pandemia est\u00e1 mais calma e vamos voltar a ter uma vida mais normal. N\u00e3o sei bem o que \u00e9 uma vida normal \u2013 e nem sei se a desejo assim tanto -, mas n\u00e3o parece que possamos voltar ao tempo que era antes. A for\u00e7a normativa da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Selected News\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-14T04:36:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-14T04:36:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/05\/Assim-se-ve-a-forca-do-PC-Meios.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1732\" \/>\n\t<meta property=\"og:image:height\" content=\"1154\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"selectednews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"selectednews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\\\/\"},\"author\":{\"name\":\"selectednews\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"headline\":\"O ador\u00e1vel mundo da dist\u00e2ncia e da proximidade &#8211; Meios &#038; Publicidade\",\"datePublished\":\"2021-06-14T04:36:44+00:00\",\"dateModified\":\"2021-06-14T04:36:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\\\/\"},\"wordCount\":777,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/Assim-se-ve-a-forca-do-PC-Meios.jpg\",\"articleSection\":[\"TEND\u00caNCIAS DE MARKETING ONLINE\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/pt\\\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\\\/\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\\\/\",\"name\":\"O ador\u00e1vel mundo da dist\u00e2ncia e da proximidade - Meios & Publicidade - Selected News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/Assim-se-ve-a-forca-do-PC-Meios.jpg\",\"datePublished\":\"2021-06-14T04:36:44+00:00\",\"dateModified\":\"2021-06-14T04:36:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/pt\\\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/Assim-se-ve-a-forca-do-PC-Meios.jpg\",\"contentUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/Assim-se-ve-a-forca-do-PC-Meios.jpg\",\"width\":1732,\"height\":1154,\"caption\":\"Assim se v\u00ea a for\u00e7a do PC - Meios & Publicidade\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O ador\u00e1vel mundo da dist\u00e2ncia e da proximidade &#8211; Meios &#038; Publicidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/\",\"name\":\"Selected News\",\"description\":\"Selected News Portugal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\",\"name\":\"selectednews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"caption\":\"selectednews\"},\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O ador\u00e1vel mundo da dist\u00e2ncia e da proximidade - Meios & Publicidade - Selected News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/","og_locale":"pt_PT","og_type":"article","og_title":"O ador\u00e1vel mundo da dist\u00e2ncia e da proximidade - Meios & Publicidade - Selected News","og_description":"V\u00edtor Cunha, administrador da JLM&amp;Associados Dizem que a pandemia est\u00e1 mais calma e vamos voltar a ter uma vida mais normal. N\u00e3o sei bem o que \u00e9 uma vida normal \u2013 e nem sei se a desejo assim tanto -, mas n\u00e3o parece que possamos voltar ao tempo que era antes. A for\u00e7a normativa da [&hellip;]","og_url":"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/","og_site_name":"Selected News","article_published_time":"2021-06-14T04:36:44+00:00","article_modified_time":"2021-06-14T04:36:47+00:00","og_image":[{"width":1732,"height":1154,"url":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/05\/Assim-se-ve-a-forca-do-PC-Meios.jpg","type":"image\/jpeg"}],"author":"selectednews","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"selectednews","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/#article","isPartOf":{"@id":"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/"},"author":{"name":"selectednews","@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"headline":"O ador\u00e1vel mundo da dist\u00e2ncia e da proximidade &#8211; Meios &#038; Publicidade","datePublished":"2021-06-14T04:36:44+00:00","dateModified":"2021-06-14T04:36:47+00:00","mainEntityOfPage":{"@id":"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/"},"wordCount":777,"commentCount":0,"image":{"@id":"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/05\/Assim-se-ve-a-forca-do-PC-Meios.jpg","articleSection":["TEND\u00caNCIAS DE MARKETING ONLINE"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/","url":"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/","name":"O ador\u00e1vel mundo da dist\u00e2ncia e da proximidade - Meios & Publicidade - Selected News","isPartOf":{"@id":"https:\/\/selectednews.info\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/#primaryimage"},"image":{"@id":"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/05\/Assim-se-ve-a-forca-do-PC-Meios.jpg","datePublished":"2021-06-14T04:36:44+00:00","dateModified":"2021-06-14T04:36:47+00:00","author":{"@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"breadcrumb":{"@id":"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/#primaryimage","url":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/05\/Assim-se-ve-a-forca-do-PC-Meios.jpg","contentUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/05\/Assim-se-ve-a-forca-do-PC-Meios.jpg","width":1732,"height":1154,"caption":"Assim se v\u00ea a for\u00e7a do PC - Meios & Publicidade"},{"@type":"BreadcrumbList","@id":"https:\/\/selectednews.info\/pt\/o-adoravel-mundo-da-distancia-e-da-proximidade-meios-publicidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/selectednews.info\/pt\/"},{"@type":"ListItem","position":2,"name":"O ador\u00e1vel mundo da dist\u00e2ncia e da proximidade &#8211; Meios &#038; Publicidade"}]},{"@type":"WebSite","@id":"https:\/\/selectednews.info\/pt\/#website","url":"https:\/\/selectednews.info\/pt\/","name":"Selected News","description":"Selected News Portugal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/selectednews.info\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068","name":"selectednews","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","caption":"selectednews"},"url":"https:\/\/selectednews.info\/pt\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/comments?post=7075"}],"version-history":[{"count":1,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7075\/revisions"}],"predecessor-version":[{"id":7076,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7075\/revisions\/7076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/media\/6888"}],"wp:attachment":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/media?parent=7075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/categories?post=7075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/tags?post=7075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}