{"id":7091,"date":"2021-06-15T19:52:59","date_gmt":"2021-06-15T16:52:59","guid":{"rendered":"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/"},"modified":"2021-06-15T19:53:03","modified_gmt":"2021-06-15T16:53:03","slug":"novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade","status":"publish","type":"post","link":"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/","title":{"rendered":"Novo projecto de forma\u00e7\u00e3o em comunica\u00e7\u00e3o une Portugal e Brasil &#8211; Meios &#038; Publicidade"},"content":{"rendered":"<p>\t\t\t\tPor Rui Oliveira Marques a 15 de Junho de 2021<\/p>\n<p>\t\t\tChama-se Conhecimento Conexo e apresenta-se como o primeiro projecto luso-brasileiro especializado em forma\u00e7\u00e3o e conhecimento na \u00e1rea da comunica\u00e7\u00e3o.<br \/>\nO Conhecimento Conexo nasce da iniciativa de Alda Benamor, portuguesa e directora-geral da consultora PLUG More, de Ja\u00edra Reis, brasileira e directora executiva da ag\u00eancia brasileira N\u00f3s da Comunica\u00e7\u00e3o e de Paulo Clemen, com dupla nacionalidade, autor e director de planeamento da N\u00f3s da Comunica\u00e7\u00e3o.<br \/>\nA\u00a0Conhecimento Conexo\u00a0\u00e9 lan\u00e7ada com cerca de 30 forma\u00e7\u00f5es online em tr\u00eas formatos: curta dura\u00e7\u00e3o (uma sess\u00e3o \u00fanica com duas horas), m\u00e9dia dura\u00e7\u00e3o (tr\u00eas sess\u00f5es com duas horas cada) e longa dura\u00e7\u00e3o (cinco sess\u00f5es com duas horas cada). Apesar de a principal componente da Conhecimento Conexo serem os cursos online, est\u00e3o previstas forma\u00e7\u00f5es \u00e0 medida e presenciais.<br \/>\n\u201cA Conhecimento Conexo\u00a0pretende fazer literalmente conex\u00f5es, n\u00e3o s\u00f3 entre as v\u00e1rias \u00e1reas do conhecimento dentro da comunica\u00e7\u00e3o empresarial e interpessoal, mas tamb\u00e9m entre estes dois pa\u00edses, Portugal e Brasil, que, apesar de separados por um oceano, usufruem de um mesmo idioma e de uma hist\u00f3ria que se cruza\u201d, descreve Alda Benamor, em comunicado.<\/p>\n<p>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.meiosepublicidade.pt\/2021\/06\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil\/?utm_source=rss&#038;utm_medium=rss&#038;utm_campaign=novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Rui Oliveira Marques a 15 de Junho de 2021 Chama-se Conhecimento Conexo e apresenta-se como o primeiro projecto luso-brasileiro especializado em forma\u00e7\u00e3o e conhecimento na \u00e1rea da comunica\u00e7\u00e3o. O Conhecimento Conexo nasce da iniciativa de Alda Benamor, portuguesa e directora-geral da consultora PLUG More, de Ja\u00edra Reis, brasileira e directora executiva da ag\u00eancia brasileira [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7092,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7091","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias-de-marketing-online"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novo projecto de forma\u00e7\u00e3o em comunica\u00e7\u00e3o une Portugal e Brasil - Meios &amp; Publicidade - Selected News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novo projecto de forma\u00e7\u00e3o em comunica\u00e7\u00e3o une Portugal e Brasil - Meios &amp; Publicidade - Selected News\" \/>\n<meta property=\"og:description\" content=\"Por Rui Oliveira Marques a 15 de Junho de 2021 Chama-se Conhecimento Conexo e apresenta-se como o primeiro projecto luso-brasileiro especializado em forma\u00e7\u00e3o e conhecimento na \u00e1rea da comunica\u00e7\u00e3o. O Conhecimento Conexo nasce da iniciativa de Alda Benamor, portuguesa e directora-geral da consultora PLUG More, de Ja\u00edra Reis, brasileira e directora executiva da ag\u00eancia brasileira [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Selected News\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-15T16:52:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-15T16:53:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/06\/Novo-projecto-de-formacao-em-comunicacao-une-Portugal-e-Brasil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1772\" \/>\n\t<meta property=\"og:image:height\" content=\"1181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"selectednews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"selectednews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\\\/\"},\"author\":{\"name\":\"selectednews\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"headline\":\"Novo projecto de forma\u00e7\u00e3o em comunica\u00e7\u00e3o une Portugal e Brasil &#8211; Meios &#038; Publicidade\",\"datePublished\":\"2021-06-15T16:52:59+00:00\",\"dateModified\":\"2021-06-15T16:53:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\\\/\"},\"wordCount\":226,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/Novo-projecto-de-formacao-em-comunicacao-une-Portugal-e-Brasil.jpg\",\"articleSection\":[\"TEND\u00caNCIAS DE MARKETING ONLINE\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/pt\\\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\\\/\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\\\/\",\"name\":\"Novo projecto de forma\u00e7\u00e3o em comunica\u00e7\u00e3o une Portugal e Brasil - Meios & Publicidade - Selected News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/Novo-projecto-de-formacao-em-comunicacao-une-Portugal-e-Brasil.jpg\",\"datePublished\":\"2021-06-15T16:52:59+00:00\",\"dateModified\":\"2021-06-15T16:53:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/pt\\\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/Novo-projecto-de-formacao-em-comunicacao-une-Portugal-e-Brasil.jpg\",\"contentUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/Novo-projecto-de-formacao-em-comunicacao-une-Portugal-e-Brasil.jpg\",\"width\":1772,\"height\":1181,\"caption\":\"Novo projecto de forma\u00e7\u00e3o em comunica\u00e7\u00e3o une Portugal e Brasil - Meios & Publicidade\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novo projecto de forma\u00e7\u00e3o em comunica\u00e7\u00e3o une Portugal e Brasil &#8211; Meios &#038; Publicidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/\",\"name\":\"Selected News\",\"description\":\"Selected News Portugal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\",\"name\":\"selectednews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"caption\":\"selectednews\"},\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novo projecto de forma\u00e7\u00e3o em comunica\u00e7\u00e3o une Portugal e Brasil - Meios & Publicidade - Selected News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/","og_locale":"pt_PT","og_type":"article","og_title":"Novo projecto de forma\u00e7\u00e3o em comunica\u00e7\u00e3o une Portugal e Brasil - Meios & Publicidade - Selected News","og_description":"Por Rui Oliveira Marques a 15 de Junho de 2021 Chama-se Conhecimento Conexo e apresenta-se como o primeiro projecto luso-brasileiro especializado em forma\u00e7\u00e3o e conhecimento na \u00e1rea da comunica\u00e7\u00e3o. O Conhecimento Conexo nasce da iniciativa de Alda Benamor, portuguesa e directora-geral da consultora PLUG More, de Ja\u00edra Reis, brasileira e directora executiva da ag\u00eancia brasileira [&hellip;]","og_url":"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/","og_site_name":"Selected News","article_published_time":"2021-06-15T16:52:59+00:00","article_modified_time":"2021-06-15T16:53:03+00:00","og_image":[{"width":1772,"height":1181,"url":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/06\/Novo-projecto-de-formacao-em-comunicacao-une-Portugal-e-Brasil.jpg","type":"image\/jpeg"}],"author":"selectednews","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"selectednews","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/#article","isPartOf":{"@id":"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/"},"author":{"name":"selectednews","@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"headline":"Novo projecto de forma\u00e7\u00e3o em comunica\u00e7\u00e3o une Portugal e Brasil &#8211; Meios &#038; Publicidade","datePublished":"2021-06-15T16:52:59+00:00","dateModified":"2021-06-15T16:53:03+00:00","mainEntityOfPage":{"@id":"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/"},"wordCount":226,"commentCount":0,"image":{"@id":"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/06\/Novo-projecto-de-formacao-em-comunicacao-une-Portugal-e-Brasil.jpg","articleSection":["TEND\u00caNCIAS DE MARKETING ONLINE"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/","url":"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/","name":"Novo projecto de forma\u00e7\u00e3o em comunica\u00e7\u00e3o une Portugal e Brasil - Meios & Publicidade - Selected News","isPartOf":{"@id":"https:\/\/selectednews.info\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/#primaryimage"},"image":{"@id":"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/06\/Novo-projecto-de-formacao-em-comunicacao-une-Portugal-e-Brasil.jpg","datePublished":"2021-06-15T16:52:59+00:00","dateModified":"2021-06-15T16:53:03+00:00","author":{"@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"breadcrumb":{"@id":"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/#primaryimage","url":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/06\/Novo-projecto-de-formacao-em-comunicacao-une-Portugal-e-Brasil.jpg","contentUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/06\/Novo-projecto-de-formacao-em-comunicacao-une-Portugal-e-Brasil.jpg","width":1772,"height":1181,"caption":"Novo projecto de forma\u00e7\u00e3o em comunica\u00e7\u00e3o une Portugal e Brasil - Meios & Publicidade"},{"@type":"BreadcrumbList","@id":"https:\/\/selectednews.info\/pt\/novo-projecto-de-formacao-em-comunicacao-une-portugal-e-brasil-meios-publicidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/selectednews.info\/pt\/"},{"@type":"ListItem","position":2,"name":"Novo projecto de forma\u00e7\u00e3o em comunica\u00e7\u00e3o une Portugal e Brasil &#8211; Meios &#038; Publicidade"}]},{"@type":"WebSite","@id":"https:\/\/selectednews.info\/pt\/#website","url":"https:\/\/selectednews.info\/pt\/","name":"Selected News","description":"Selected News Portugal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/selectednews.info\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068","name":"selectednews","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","caption":"selectednews"},"url":"https:\/\/selectednews.info\/pt\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/comments?post=7091"}],"version-history":[{"count":1,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7091\/revisions"}],"predecessor-version":[{"id":7093,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7091\/revisions\/7093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/media\/7092"}],"wp:attachment":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/media?parent=7091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/categories?post=7091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/tags?post=7091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}