{"id":7281,"date":"2021-07-02T10:19:03","date_gmt":"2021-07-02T07:19:03","guid":{"rendered":"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/"},"modified":"2021-07-02T10:19:07","modified_gmt":"2021-07-02T07:19:07","slug":"profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade","status":"publish","type":"post","link":"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/","title":{"rendered":"Profissionais dos eventos e festivais voltaram \u00e0 rua contra medidas que est\u00e3o a \u201cestrangular um sector fundamental para o pa\u00eds\u201d &#8211; Meios &#038; Publicidade"},"content":{"rendered":"<p>\t\t\t\u201cEstamos a estrangular um sector fundamental para o pa\u00eds\u201d, alertou Pedro Magalh\u00e3es, presidente da APSTE (Associa\u00e7\u00e3o Portuguesa de Servi\u00e7os para Eventos), \u00e0 qual se juntou a APEFE (Associa\u00e7\u00e3o de Promotores de Espect\u00e1culos, Festivais e Eventos), numa manifesta\u00e7\u00e3o que trouxe de volta \u00e0s ruas de Lisboa as caixas negras dos profissionais do sector dos eventos. O protesto, que arrancou na pra\u00e7a do Marqu\u00eas de Pombal e percorreu a Avenida da Liberdade at\u00e9 aos Restauradores, surge na sequ\u00eancia das \u201cmais recentes medidas divulgadas pelo governo e pela DGS, que determinam a obrigatoriedade de testes \u00e0 covid-19 para os diferentes tipos de eventos, sem assumir as despesas inerentes\u201d, bem como a aus\u00eancia de conclus\u00f5es na sequ\u00eancia da iniciativa dos eventos-piloto. As associa\u00e7\u00f5es consideram, por isso, que \u201cn\u00e3o existe por parte do executivo uma estrat\u00e9gia concertada para apoiar o sector\u201d.<br \/>\nA manifesta\u00e7\u00e3o teve como objectivo \u201cchamar a aten\u00e7\u00e3o do governo para a necessidade urgente de criar medidas concretas que, de alguma forma, consigam garantir a subsist\u00eancia das empresas que, com todas as medidas impostas no decurso da pandemia covid-19, encontram-se em estado muito cr\u00edtico, estando muito perto de fechar portas\u201d.<br \/>\n\u201cA situa\u00e7\u00e3o que vivemos neste sector \u00e9 desesperante. Depois de mais de um ano sem trabalhar, as empresas n\u00e3o conseguem subsistir. Queremos uma estrat\u00e9gia, queremos trabalhar em conjunto com o governo para encontrar solu\u00e7\u00f5es, mas o que percebemos \u00e9 que as nossas reuni\u00f5es n\u00e3o t\u00eam dado frutos. N\u00e3o nos est\u00e3o a ouvir\u201d, aponta Pedro Magalh\u00e3es, alertando que \u201ca continuarmos assim, quando efectivamente conseguirmos voltar a fazer eventos, muitas empresas j\u00e1 n\u00e3o v\u00e3o conseguir fazer parte da retoma\u201d.<br \/>\nSobre as quest\u00f5es dos testes obrigat\u00f3rios e do atraso no tratamento dos dados relativos aos eventos-piloto realizados em Abril e Maio, o presidente da APSTE questiona \u201ccomo \u00e9 poss\u00edvel determinar-se a obrigatoriedade de testes \u00e0 covid-19 para os diferentes tipos de eventos sem assumir as despesas inerentes\u201d. \u201cMais uma vez n\u00e3o percebemos. Tivemos conhecimento, h\u00e1 poucos momentos, que o governo reconsiderou esta medida, mas mais uma vez repito, \u00e9 necess\u00e1rio chegarmos a este ponto? \u00c9 necess\u00e1rio virmos para a rua para finalmente serem aprovadas medidas que de alguma forma impactem positivamente o nosso sector?\u201d prosseguiu, sublinhando que \u201cmais uma vez, a aus\u00eancia de estrat\u00e9gia e de efectividade \u00e9 gritante\u201d.<\/p>\n<p>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.meiosepublicidade.pt\/2021\/07\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais\/?utm_source=rss&#038;utm_medium=rss&#038;utm_campaign=profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEstamos a estrangular um sector fundamental para o pa\u00eds\u201d, alertou Pedro Magalh\u00e3es, presidente da APSTE (Associa\u00e7\u00e3o Portuguesa de Servi\u00e7os para Eventos), \u00e0 qual se juntou a APEFE (Associa\u00e7\u00e3o de Promotores de Espect\u00e1culos, Festivais e Eventos), numa manifesta\u00e7\u00e3o que trouxe de volta \u00e0s ruas de Lisboa as caixas negras dos profissionais do sector dos eventos. O [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7282,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias-de-marketing-online"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Profissionais dos eventos e festivais voltaram \u00e0 rua contra medidas que est\u00e3o a \u201cestrangular um sector fundamental para o pa\u00eds\u201d - Meios &amp; Publicidade - Selected News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Profissionais dos eventos e festivais voltaram \u00e0 rua contra medidas que est\u00e3o a \u201cestrangular um sector fundamental para o pa\u00eds\u201d - Meios &amp; Publicidade - Selected News\" \/>\n<meta property=\"og:description\" content=\"\u201cEstamos a estrangular um sector fundamental para o pa\u00eds\u201d, alertou Pedro Magalh\u00e3es, presidente da APSTE (Associa\u00e7\u00e3o Portuguesa de Servi\u00e7os para Eventos), \u00e0 qual se juntou a APEFE (Associa\u00e7\u00e3o de Promotores de Espect\u00e1culos, Festivais e Eventos), numa manifesta\u00e7\u00e3o que trouxe de volta \u00e0s ruas de Lisboa as caixas negras dos profissionais do sector dos eventos. O [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Selected News\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-02T07:19:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-02T07:19:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/Profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"selectednews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"selectednews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\\\/\"},\"author\":{\"name\":\"selectednews\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"headline\":\"Profissionais dos eventos e festivais voltaram \u00e0 rua contra medidas que est\u00e3o a \u201cestrangular um sector fundamental para o pa\u00eds\u201d &#8211; Meios &#038; Publicidade\",\"datePublished\":\"2021-07-02T07:19:03+00:00\",\"dateModified\":\"2021-07-02T07:19:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\\\/\"},\"wordCount\":429,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/Profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas.jpg\",\"articleSection\":[\"TEND\u00caNCIAS DE MARKETING ONLINE\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/pt\\\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\\\/\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\\\/\",\"name\":\"Profissionais dos eventos e festivais voltaram \u00e0 rua contra medidas que est\u00e3o a \u201cestrangular um sector fundamental para o pa\u00eds\u201d - Meios & Publicidade - Selected News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/Profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas.jpg\",\"datePublished\":\"2021-07-02T07:19:03+00:00\",\"dateModified\":\"2021-07-02T07:19:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/pt\\\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/Profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas.jpg\",\"contentUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/Profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas.jpg\",\"width\":1000,\"height\":665,\"caption\":\"Profissionais dos eventos e festivais voltaram \u00e0 rua contra medidas que est\u00e3o a \u201cestrangular um sector fundamental para o pa\u00eds\u201d - Meios & Publicidade\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Profissionais dos eventos e festivais voltaram \u00e0 rua contra medidas que est\u00e3o a \u201cestrangular um sector fundamental para o pa\u00eds\u201d &#8211; Meios &#038; Publicidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/\",\"name\":\"Selected News\",\"description\":\"Selected News Portugal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\",\"name\":\"selectednews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"caption\":\"selectednews\"},\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Profissionais dos eventos e festivais voltaram \u00e0 rua contra medidas que est\u00e3o a \u201cestrangular um sector fundamental para o pa\u00eds\u201d - Meios & Publicidade - Selected News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/","og_locale":"pt_PT","og_type":"article","og_title":"Profissionais dos eventos e festivais voltaram \u00e0 rua contra medidas que est\u00e3o a \u201cestrangular um sector fundamental para o pa\u00eds\u201d - Meios & Publicidade - Selected News","og_description":"\u201cEstamos a estrangular um sector fundamental para o pa\u00eds\u201d, alertou Pedro Magalh\u00e3es, presidente da APSTE (Associa\u00e7\u00e3o Portuguesa de Servi\u00e7os para Eventos), \u00e0 qual se juntou a APEFE (Associa\u00e7\u00e3o de Promotores de Espect\u00e1culos, Festivais e Eventos), numa manifesta\u00e7\u00e3o que trouxe de volta \u00e0s ruas de Lisboa as caixas negras dos profissionais do sector dos eventos. O [&hellip;]","og_url":"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/","og_site_name":"Selected News","article_published_time":"2021-07-02T07:19:03+00:00","article_modified_time":"2021-07-02T07:19:07+00:00","og_image":[{"width":1000,"height":665,"url":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/Profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas.jpg","type":"image\/jpeg"}],"author":"selectednews","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"selectednews","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/#article","isPartOf":{"@id":"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/"},"author":{"name":"selectednews","@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"headline":"Profissionais dos eventos e festivais voltaram \u00e0 rua contra medidas que est\u00e3o a \u201cestrangular um sector fundamental para o pa\u00eds\u201d &#8211; Meios &#038; Publicidade","datePublished":"2021-07-02T07:19:03+00:00","dateModified":"2021-07-02T07:19:07+00:00","mainEntityOfPage":{"@id":"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/"},"wordCount":429,"commentCount":0,"image":{"@id":"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/Profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas.jpg","articleSection":["TEND\u00caNCIAS DE MARKETING ONLINE"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/","url":"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/","name":"Profissionais dos eventos e festivais voltaram \u00e0 rua contra medidas que est\u00e3o a \u201cestrangular um sector fundamental para o pa\u00eds\u201d - Meios & Publicidade - Selected News","isPartOf":{"@id":"https:\/\/selectednews.info\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/#primaryimage"},"image":{"@id":"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/Profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas.jpg","datePublished":"2021-07-02T07:19:03+00:00","dateModified":"2021-07-02T07:19:07+00:00","author":{"@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"breadcrumb":{"@id":"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/#primaryimage","url":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/Profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas.jpg","contentUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/Profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas.jpg","width":1000,"height":665,"caption":"Profissionais dos eventos e festivais voltaram \u00e0 rua contra medidas que est\u00e3o a \u201cestrangular um sector fundamental para o pa\u00eds\u201d - Meios & Publicidade"},{"@type":"BreadcrumbList","@id":"https:\/\/selectednews.info\/pt\/profissionais-dos-eventos-e-festivais-voltaram-a-rua-contra-medidas-que-estao-a-estrangular-um-sector-fundamental-para-o-pais-meios-publicidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/selectednews.info\/pt\/"},{"@type":"ListItem","position":2,"name":"Profissionais dos eventos e festivais voltaram \u00e0 rua contra medidas que est\u00e3o a \u201cestrangular um sector fundamental para o pa\u00eds\u201d &#8211; Meios &#038; Publicidade"}]},{"@type":"WebSite","@id":"https:\/\/selectednews.info\/pt\/#website","url":"https:\/\/selectednews.info\/pt\/","name":"Selected News","description":"Selected News Portugal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/selectednews.info\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068","name":"selectednews","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","caption":"selectednews"},"url":"https:\/\/selectednews.info\/pt\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/comments?post=7281"}],"version-history":[{"count":1,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7281\/revisions"}],"predecessor-version":[{"id":7283,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7281\/revisions\/7283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/media\/7282"}],"wp:attachment":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/media?parent=7281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/categories?post=7281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/tags?post=7281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}