{"id":7326,"date":"2021-07-06T10:49:43","date_gmt":"2021-07-06T07:49:43","guid":{"rendered":"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/"},"modified":"2021-07-06T10:49:46","modified_gmt":"2021-07-06T07:49:46","slug":"galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade","status":"publish","type":"post","link":"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/","title":{"rendered":"Galp contrata Jo\u00e3o Pedro Machado para assegurar \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d &#8211; Meios &#038; Publicidade"},"content":{"rendered":"<p>\t\t\t\tPor Pedro Dur\u00e3es a 5 de Julho de 2021<\/p>\n<p>\t\t\tA \u201cincorpora\u00e7\u00e3o de modelos de analytics e intelig\u00eancia artificial\u201d, a par da \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d da Galp, est\u00e3o entre os objectivos tra\u00e7ados para o novo head of offer &amp; transformation da energ\u00e9tica. At\u00e9 aqui CEO da OK! Teleseguros e head of transformation da Fidelidade, Jo\u00e3o Pedro Machado chega com a miss\u00e3o de \u201cgarantir a defini\u00e7\u00e3o de propostas de valor end-to-end para os clientes e consumidores da Galp, com particular foco sobre os produtos e servi\u00e7os, suas caracter\u00edsticas, pricing, canais de comunica\u00e7\u00e3o e promo\u00e7\u00e3o\u201d.<br \/>\nSalientando que a empresa est\u00e1 a \u201cliderar a tomada decis\u00f5es e a fazer investimentos que formam o futuro da energia, da mobilidade, da nossa vida\u201d, Jo\u00e3o Pedro Machado explica que \u201cisto est\u00e1 a acontecer num momento em que a transforma\u00e7\u00e3o digital \u00e9 transversal \u00e0 sociedade e \u00e0 economia e em que os clientes t\u00eam uma exig\u00eancia cada vez maior com as marcas e com as experi\u00eancias que estas lhes proporcionam\u201d. \u201cEsse movimento obriga a um desenvolvimento sustentado das propriedades digitais da Galp ao servi\u00e7o dos seus clientes, de forma a refor\u00e7ar o seu posicionamento enquanto o parceiro de elei\u00e7\u00e3o\u201d, argumenta, em comunicado, o respons\u00e1vel.<br \/>\nNesse sentido, al\u00e9m de assumir o cargo com o objectivo de, em articula\u00e7\u00e3o com as equipas B2B e B2C, \u201cconstruir propostas diferenciadoras que permitam atingir os objectivos comerciais multiproduto da Galp, contribuindo para uma maximiza\u00e7\u00e3o sustent\u00e1vel das vendas, impulsionada pela crescente centraliza\u00e7\u00e3o nos clientes, actuais e futuros\u201d, Jo\u00e3o Pedro Machado ser\u00e1 igualmente respons\u00e1vel, na vertente de transforma\u00e7\u00e3o, \u201cpelo desenvolvimento de processos internos da \u00e1rea comercial, incorpora\u00e7\u00e3o de modelos de analytics e intelig\u00eancia artificial, bem como pela transforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais, procurando solu\u00e7\u00f5es e modelos de neg\u00f3cio inovadores e disruptivos para serem desenvolvidos comercialmente\u201d.<\/p>\n<p>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.meiosepublicidade.pt\/2021\/07\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais\/?utm_source=rss&#038;utm_medium=rss&#038;utm_campaign=galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Pedro Dur\u00e3es a 5 de Julho de 2021 A \u201cincorpora\u00e7\u00e3o de modelos de analytics e intelig\u00eancia artificial\u201d, a par da \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d da Galp, est\u00e3o entre os objectivos tra\u00e7ados para o novo head of offer &amp; transformation da energ\u00e9tica. At\u00e9 aqui CEO da OK! Teleseguros e head of transformation da Fidelidade, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7327,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias-de-marketing-online"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Galp contrata Jo\u00e3o Pedro Machado para assegurar \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d - Meios &amp; Publicidade - Selected News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Galp contrata Jo\u00e3o Pedro Machado para assegurar \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d - Meios &amp; Publicidade - Selected News\" \/>\n<meta property=\"og:description\" content=\"Por Pedro Dur\u00e3es a 5 de Julho de 2021 A \u201cincorpora\u00e7\u00e3o de modelos de analytics e intelig\u00eancia artificial\u201d, a par da \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d da Galp, est\u00e3o entre os objectivos tra\u00e7ados para o novo head of offer &amp; transformation da energ\u00e9tica. At\u00e9 aqui CEO da OK! Teleseguros e head of transformation da Fidelidade, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Selected News\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-06T07:49:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-06T07:49:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/Galp-contrata-Joao-Pedro-Machado-para-assegurar-transformacao-digital-das.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"795\" \/>\n\t<meta property=\"og:image:height\" content=\"611\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"selectednews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"selectednews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\\\/\"},\"author\":{\"name\":\"selectednews\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"headline\":\"Galp contrata Jo\u00e3o Pedro Machado para assegurar \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d &#8211; Meios &#038; Publicidade\",\"datePublished\":\"2021-07-06T07:49:43+00:00\",\"dateModified\":\"2021-07-06T07:49:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\\\/\"},\"wordCount\":348,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/Galp-contrata-Joao-Pedro-Machado-para-assegurar-transformacao-digital-das.jpg\",\"articleSection\":[\"TEND\u00caNCIAS DE MARKETING ONLINE\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/pt\\\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\\\/\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\\\/\",\"name\":\"Galp contrata Jo\u00e3o Pedro Machado para assegurar \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d - Meios & Publicidade - Selected News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/Galp-contrata-Joao-Pedro-Machado-para-assegurar-transformacao-digital-das.jpg\",\"datePublished\":\"2021-07-06T07:49:43+00:00\",\"dateModified\":\"2021-07-06T07:49:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/pt\\\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/Galp-contrata-Joao-Pedro-Machado-para-assegurar-transformacao-digital-das.jpg\",\"contentUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/Galp-contrata-Joao-Pedro-Machado-para-assegurar-transformacao-digital-das.jpg\",\"width\":795,\"height\":611,\"caption\":\"Galp contrata Jo\u00e3o Pedro Machado para assegurar \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d - Meios & Publicidade\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galp contrata Jo\u00e3o Pedro Machado para assegurar \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d &#8211; Meios &#038; Publicidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/\",\"name\":\"Selected News\",\"description\":\"Selected News Portugal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\",\"name\":\"selectednews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"caption\":\"selectednews\"},\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Galp contrata Jo\u00e3o Pedro Machado para assegurar \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d - Meios & Publicidade - Selected News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/","og_locale":"pt_PT","og_type":"article","og_title":"Galp contrata Jo\u00e3o Pedro Machado para assegurar \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d - Meios & Publicidade - Selected News","og_description":"Por Pedro Dur\u00e3es a 5 de Julho de 2021 A \u201cincorpora\u00e7\u00e3o de modelos de analytics e intelig\u00eancia artificial\u201d, a par da \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d da Galp, est\u00e3o entre os objectivos tra\u00e7ados para o novo head of offer &amp; transformation da energ\u00e9tica. At\u00e9 aqui CEO da OK! Teleseguros e head of transformation da Fidelidade, [&hellip;]","og_url":"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/","og_site_name":"Selected News","article_published_time":"2021-07-06T07:49:43+00:00","article_modified_time":"2021-07-06T07:49:46+00:00","og_image":[{"width":795,"height":611,"url":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/Galp-contrata-Joao-Pedro-Machado-para-assegurar-transformacao-digital-das.jpg","type":"image\/jpeg"}],"author":"selectednews","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"selectednews","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/#article","isPartOf":{"@id":"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/"},"author":{"name":"selectednews","@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"headline":"Galp contrata Jo\u00e3o Pedro Machado para assegurar \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d &#8211; Meios &#038; Publicidade","datePublished":"2021-07-06T07:49:43+00:00","dateModified":"2021-07-06T07:49:46+00:00","mainEntityOfPage":{"@id":"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/"},"wordCount":348,"commentCount":0,"image":{"@id":"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/Galp-contrata-Joao-Pedro-Machado-para-assegurar-transformacao-digital-das.jpg","articleSection":["TEND\u00caNCIAS DE MARKETING ONLINE"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/","url":"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/","name":"Galp contrata Jo\u00e3o Pedro Machado para assegurar \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d - Meios & Publicidade - Selected News","isPartOf":{"@id":"https:\/\/selectednews.info\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/#primaryimage"},"image":{"@id":"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/Galp-contrata-Joao-Pedro-Machado-para-assegurar-transformacao-digital-das.jpg","datePublished":"2021-07-06T07:49:43+00:00","dateModified":"2021-07-06T07:49:46+00:00","author":{"@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"breadcrumb":{"@id":"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/#primaryimage","url":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/Galp-contrata-Joao-Pedro-Machado-para-assegurar-transformacao-digital-das.jpg","contentUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/Galp-contrata-Joao-Pedro-Machado-para-assegurar-transformacao-digital-das.jpg","width":795,"height":611,"caption":"Galp contrata Jo\u00e3o Pedro Machado para assegurar \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d - Meios & Publicidade"},{"@type":"BreadcrumbList","@id":"https:\/\/selectednews.info\/pt\/galp-contrata-joao-pedro-machado-para-assegurar-transformacao-digital-das-solucoes-comerciais-meios-publicidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/selectednews.info\/pt\/"},{"@type":"ListItem","position":2,"name":"Galp contrata Jo\u00e3o Pedro Machado para assegurar \u201ctransforma\u00e7\u00e3o digital das solu\u00e7\u00f5es comerciais\u201d &#8211; Meios &#038; Publicidade"}]},{"@type":"WebSite","@id":"https:\/\/selectednews.info\/pt\/#website","url":"https:\/\/selectednews.info\/pt\/","name":"Selected News","description":"Selected News Portugal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/selectednews.info\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068","name":"selectednews","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","caption":"selectednews"},"url":"https:\/\/selectednews.info\/pt\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/comments?post=7326"}],"version-history":[{"count":1,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7326\/revisions"}],"predecessor-version":[{"id":7328,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7326\/revisions\/7328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/media\/7327"}],"wp:attachment":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/media?parent=7326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/categories?post=7326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/tags?post=7326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}