{"id":7338,"date":"2021-07-07T11:02:12","date_gmt":"2021-07-07T08:02:12","guid":{"rendered":"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/"},"modified":"2021-07-07T11:02:18","modified_gmt":"2021-07-07T08:02:18","slug":"5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade","status":"publish","type":"post","link":"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/","title":{"rendered":"5002&#038;Beyond regista marca Passagem do Meio do Ano &#8211; Meios &#038; Publicidade"},"content":{"rendered":"<p>\t\t\t\tPor Rui Oliveira Marques a 6 de Julho de 2021<\/p>\n<p>\t\t\tFernanda Dias de Assun\u00e7\u00e3o e Jorge Coelho<br \/>\nA ag\u00eancia 5002&amp;Beyond est\u00e1 a desenvolver o conceito e marca Passagem do Meio do Ano, que pretende celebrar a data em que se assinala a metade do ano. As conting\u00eancias da pandemia s\u00f3 permitiram que no passado dia 2 de Julho a data fosse assinalada com um grupo pequeno de pessoas, mas a expectativa \u00e9 que o projecto possa ganhar escala.<br \/>\n\u201cPensado como uma oportunidade para criar um novo momento de conversa e tamb\u00e9m de consumo para algumas marcas, a marca Passagem do Meio do Ano surge como uma oportunidade para desafiar as marcas com uma solu\u00e7\u00e3o para estarem mais perto dos seus consumidores e f\u00e3s, com um conceito irreverente, que promete virar o disco e tocar o lado B do ano com concertos, ativa\u00e7\u00f5es de rua e at\u00e9 festas em casa, como numa verdadeira passagem de ano\u201d, refere o comunicado da ag\u00eancia fundada por Fernanda Dias de Assun\u00e7\u00e3o e Jorge Coelho. Os respons\u00e1veis asseguram que \u201calgumas das maiores marcas nacionais est\u00e3o j\u00e1 envolvidas e o segundo semestre de 2021 vai ser de planeamento e fecho de contratos, mas h\u00e1 ainda espa\u00e7o para incluir muitas mais\u201d.<br \/>\nA ideia \u00e9 que o o conceito Passagem do Meio do Ano seja adapt\u00e1vel \u00e0s necessidades de cada marca e neg\u00f3cio. O projecto envolve uma equipa de seis profissionais das \u00e1reas de activa\u00e7\u00e3o, parcerias, media, planeamento estrat\u00e9gico e criatividade.<\/p>\n<p>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.meiosepublicidade.pt\/2021\/07\/5002beyond-regista-marca-passagem-do-meio-do-ano\/?utm_source=rss&#038;utm_medium=rss&#038;utm_campaign=5002beyond-regista-marca-passagem-do-meio-do-ano\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Rui Oliveira Marques a 6 de Julho de 2021 Fernanda Dias de Assun\u00e7\u00e3o e Jorge Coelho A ag\u00eancia 5002&amp;Beyond est\u00e1 a desenvolver o conceito e marca Passagem do Meio do Ano, que pretende celebrar a data em que se assinala a metade do ano. As conting\u00eancias da pandemia s\u00f3 permitiram que no passado dia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7339,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias-de-marketing-online"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5002&amp;Beyond regista marca Passagem do Meio do Ano - Meios &amp; Publicidade - Selected News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5002&amp;Beyond regista marca Passagem do Meio do Ano - Meios &amp; Publicidade - Selected News\" \/>\n<meta property=\"og:description\" content=\"Por Rui Oliveira Marques a 6 de Julho de 2021 Fernanda Dias de Assun\u00e7\u00e3o e Jorge Coelho A ag\u00eancia 5002&amp;Beyond est\u00e1 a desenvolver o conceito e marca Passagem do Meio do Ano, que pretende celebrar a data em que se assinala a metade do ano. As conting\u00eancias da pandemia s\u00f3 permitiram que no passado dia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Selected News\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-07T08:02:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-07T08:02:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/5002Beyond-regista-marca-Passagem-do-Meio-do-Ano-Meios.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"selectednews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"selectednews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\\\/\"},\"author\":{\"name\":\"selectednews\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"headline\":\"5002&#038;Beyond regista marca Passagem do Meio do Ano &#8211; Meios &#038; Publicidade\",\"datePublished\":\"2021-07-07T08:02:12+00:00\",\"dateModified\":\"2021-07-07T08:02:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\\\/\"},\"wordCount\":266,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/5002Beyond-regista-marca-Passagem-do-Meio-do-Ano-Meios.jpg\",\"articleSection\":[\"TEND\u00caNCIAS DE MARKETING ONLINE\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/pt\\\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\\\/\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\\\/\",\"name\":\"5002&Beyond regista marca Passagem do Meio do Ano - Meios & Publicidade - Selected News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/5002Beyond-regista-marca-Passagem-do-Meio-do-Ano-Meios.jpg\",\"datePublished\":\"2021-07-07T08:02:12+00:00\",\"dateModified\":\"2021-07-07T08:02:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/selectednews.info\\\/pt\\\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/5002Beyond-regista-marca-Passagem-do-Meio-do-Ano-Meios.jpg\",\"contentUrl\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/5002Beyond-regista-marca-Passagem-do-Meio-do-Ano-Meios.jpg\",\"width\":1600,\"height\":1067,\"caption\":\"5002&Beyond regista marca Passagem do Meio do Ano - Meios & Publicidade\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5002&#038;Beyond regista marca Passagem do Meio do Ano &#8211; Meios &#038; Publicidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/\",\"name\":\"Selected News\",\"description\":\"Selected News Portugal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/#\\\/schema\\\/person\\\/c8a0f1bfe64548cfb06c0529b0970068\",\"name\":\"selectednews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g\",\"caption\":\"selectednews\"},\"url\":\"https:\\\/\\\/selectednews.info\\\/pt\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5002&Beyond regista marca Passagem do Meio do Ano - Meios & Publicidade - Selected News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/","og_locale":"pt_PT","og_type":"article","og_title":"5002&Beyond regista marca Passagem do Meio do Ano - Meios & Publicidade - Selected News","og_description":"Por Rui Oliveira Marques a 6 de Julho de 2021 Fernanda Dias de Assun\u00e7\u00e3o e Jorge Coelho A ag\u00eancia 5002&amp;Beyond est\u00e1 a desenvolver o conceito e marca Passagem do Meio do Ano, que pretende celebrar a data em que se assinala a metade do ano. As conting\u00eancias da pandemia s\u00f3 permitiram que no passado dia [&hellip;]","og_url":"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/","og_site_name":"Selected News","article_published_time":"2021-07-07T08:02:12+00:00","article_modified_time":"2021-07-07T08:02:18+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/5002Beyond-regista-marca-Passagem-do-Meio-do-Ano-Meios.jpg","type":"image\/jpeg"}],"author":"selectednews","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"selectednews","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/#article","isPartOf":{"@id":"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/"},"author":{"name":"selectednews","@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"headline":"5002&#038;Beyond regista marca Passagem do Meio do Ano &#8211; Meios &#038; Publicidade","datePublished":"2021-07-07T08:02:12+00:00","dateModified":"2021-07-07T08:02:18+00:00","mainEntityOfPage":{"@id":"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/"},"wordCount":266,"commentCount":0,"image":{"@id":"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/5002Beyond-regista-marca-Passagem-do-Meio-do-Ano-Meios.jpg","articleSection":["TEND\u00caNCIAS DE MARKETING ONLINE"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/","url":"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/","name":"5002&Beyond regista marca Passagem do Meio do Ano - Meios & Publicidade - Selected News","isPartOf":{"@id":"https:\/\/selectednews.info\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/#primaryimage"},"image":{"@id":"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/#primaryimage"},"thumbnailUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/5002Beyond-regista-marca-Passagem-do-Meio-do-Ano-Meios.jpg","datePublished":"2021-07-07T08:02:12+00:00","dateModified":"2021-07-07T08:02:18+00:00","author":{"@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068"},"breadcrumb":{"@id":"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/#primaryimage","url":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/5002Beyond-regista-marca-Passagem-do-Meio-do-Ano-Meios.jpg","contentUrl":"https:\/\/selectednews.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/07\/5002Beyond-regista-marca-Passagem-do-Meio-do-Ano-Meios.jpg","width":1600,"height":1067,"caption":"5002&Beyond regista marca Passagem do Meio do Ano - Meios & Publicidade"},{"@type":"BreadcrumbList","@id":"https:\/\/selectednews.info\/pt\/5002beyond-regista-marca-passagem-do-meio-do-ano-meios-publicidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/selectednews.info\/pt\/"},{"@type":"ListItem","position":2,"name":"5002&#038;Beyond regista marca Passagem do Meio do Ano &#8211; Meios &#038; Publicidade"}]},{"@type":"WebSite","@id":"https:\/\/selectednews.info\/pt\/#website","url":"https:\/\/selectednews.info\/pt\/","name":"Selected News","description":"Selected News Portugal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/selectednews.info\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/selectednews.info\/pt\/#\/schema\/person\/c8a0f1bfe64548cfb06c0529b0970068","name":"selectednews","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c88515018a25fd646d9f77ea80cc88996711575667608a2cd1b47f3d1145508a?s=96&d=mm&r=g","caption":"selectednews"},"url":"https:\/\/selectednews.info\/pt\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/comments?post=7338"}],"version-history":[{"count":1,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7338\/revisions"}],"predecessor-version":[{"id":7340,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/posts\/7338\/revisions\/7340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/media\/7339"}],"wp:attachment":[{"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/media?parent=7338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/categories?post=7338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/selectednews.info\/pt\/wp-json\/wp\/v2\/tags?post=7338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}